{"id":2444,"date":"2019-02-12T03:00:21","date_gmt":"2019-02-12T02:00:21","guid":{"rendered":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/"},"modified":"2019-02-12T03:00:21","modified_gmt":"2019-02-12T02:00:21","slug":"il-numero-di-febbraio-de-il-progettista-industriale-e-online","status":"publish","type":"post","link":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/","title":{"rendered":"Il numero di febbraio de Il Progettista Industriale \u00e8 online!"},"content":{"rendered":"<div>\n<div style=\"margin: 5px 5% 10px 5%;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.ilprogettistaindustriale.it\/files\/2019\/02\/PI_2019_002_001.jpg?resize=652%2C808&#038;ssl=1\" width=\"652\" height=\"808\" title=\"\" alt=\"\"><\/div>\n<div>\n<div>\n<p>Il numero di febbraio de <em>Il progettista Industriale<\/em>, dopo la distribuzione agli abbonati nel formato cartaceo, \u00e8 ora online e scaricabile anche dalle app per iOs e Android (in fondo trovate le istruzioni per leggerlo).<\/p>\n<p>Vi segnaliamo qualche contenuto che riteniamo particolarmente interessante, a partire dall\u2019articolo intitolato<em> La sfida all\u2019Europa<\/em>. Andrea Bondi\u00a0 fa il punto sulle sfide che attendono l\u2019Unione Europea alla prova alcuni megatrend globali: invecchiamento demografico, tecnologie digitali, automazione e intelligenza artificiale, aumento della concorrenza globale, flussi migratori, cambiamento climatico e mutamento geopolitico.<\/p>\n<p>Andrea Garuglieri invece, nella sezione <em>Sbagliando si impara<\/em> si sofferma sulla progettazione di un centro di lavoro CNC per la finitura di pannelli per mobili e il suo articolo si intitola <em>Imparare sbagliando un po\u2019 meno<\/em> con l\u2019analisi FEM.<\/p>\n<p>Tra i numerosi articoli pubblicati segnaliamo infine il contributo di Stefano Monti, nella sezione <em>Primo Piano<\/em>, dedicato all\u2019ottimizzazione strutturale.<\/p>\n<\/div>\n<div>\n<p>Sono soltanto alcuni degli argomenti trattati in questo numero. Buona lettura, se credete.<\/p>\n<\/div>\n<fieldset>\n<legend>PER SAPERNE DI PI\u00d9<\/legend>\n<p>Trovi il<strong> numero di settembre <\/strong>e tutti gli altri numeri de <em>Il Progettista Industriale <\/em><strong><a href=\"http:\/\/pixelbook.tecnichenuove.com\/newsstand\/ilprogettistaindustriale\/open\/list\" target=\"_blank\" rel=\"noopener noreferrer\">qui<\/a><\/strong>. Sfoglia gratuitamente le prime venti pagine di ogni rivista. Per leggerle tutte devi <strong><a href=\"http:\/\/www.tecnichenuove.com\/il-progettista-industriale.html\" target=\"_blank\" rel=\"noopener noreferrer\">abbonarti<\/a><\/strong>. La versione digitale costa 40 euro all\u2019anno (10 numeri), mentre quella cartacea costa 50 euro.<\/p>\n<p><strong>Preferisci acquistare un numero singolo da sfogliare su tablet o smartphone?<\/strong> Puoi scaricare gratuitamente l\u2019<strong><a href=\"https:\/\/itunes.apple.com\/it\/app\/il-progettista-industriale\/id979142033?mt=8\" target=\"_blank\" rel=\"noopener noreferrer\">App per dispositivi Apple<\/a><\/strong> o l\u2019<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.tecnichenuove.ilprogettistaindustriale&#038;hl=it\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>App per dispositivi Android<\/strong><\/a>. Pagherai solo 3,99 euro per ogni numero che deciderai di leggere.<\/p>\n<\/fieldset>\n<\/div>\n<p>L&#8217;articolo <a rel=\"nofollow\" href=\"https:\/\/www.ilprogettistaindustriale.it\/il-numero-di-febbraio-de-il-progettista-industriale-e-online-2\/\">Il numero di febbraio de Il Progettista Industriale \u00e8 online!<\/a> sembra essere il primo su <a rel=\"nofollow\" href=\"https:\/\/www.ilprogettistaindustriale.it\/\">Il Progettista Industriale<\/a>.<\/p>\n<\/div>\n<p><a href=\"https:\/\/www.ilprogettistaindustriale.it\/il-numero-di-febbraio-de-il-progettista-industriale-e-online-2\/\">Vai alla fonte.<\/a><\/p>\n<p>Autore: Redazione<\/p>\n<p class=\"wpematico_credit\"><small>Powered by <a href=\"http:\/\/www.wpematico.com\" target=\"_blank\">WPeMatico<\/a><\/small><\/p>\n<p><strong>_________________________________<\/strong><\/p>\n<p><strong>CFD FEA Service SRL<\/strong> &egrave; una societ&agrave; di servizi che offre <em>consulenza<\/em> e <em>formazione<\/em> in ambito <strong>ingegneria<\/strong> e <strong>IT<\/strong>. Se questo post\/prodotto ti &egrave; piaciuto ti invitiamo a:<\/p>\n<ul>\n<li>visionare il nostro <a href=\"https:\/\/cfdfeaservice.it\/index.php\/blog\/\" target=\"_blank\" rel=\"noopener\">blog<\/a><\/li>\n<li>visionare i <a href=\"https:\/\/cfdfeaservice.it\/index.php\/prodotti\/\" target=\"_blank\" rel=\"noopener\">software<\/a> disponibili - anche per la formazione<\/li>\n<li>iscriverti alla nostra newsletter<\/li>\n<li>entrare in contatto con noi attraverso la <a href=\"https:\/\/cfdfeaservice.it\/#ribbon\" target=\"_blank\" rel=\"noopener\">pagina contatti<\/a><\/li>\n<\/ul>\n<p>Saremo lieti di seguire le tue richieste e fornire risposte alle tue domande.<\/p>","protected":false},"excerpt":{"rendered":"<p>Il numero di febbraio de Il progettista Industriale, dopo la distribuzione agli abbonati nel formato cartaceo, \u00e8 ora online e scaricabile anche dalle app per iOs e Android (in fondo trovate le istruzioni per leggerlo). Vi segnaliamo qualche contenuto che riteniamo particolarmente interessante, a partire dall\u2019articolo intitolato La sfida all\u2019Europa. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[57],"tags":[],"class_list":["post-2444","post","type-post","status-publish","format-standard","hentry","category-normativa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il numero di febbraio de Il Progettista Industriale \u00e8 online! - CFD FEA\/FEM Service<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il numero di febbraio de Il Progettista Industriale \u00e8 online! - CFD FEA\/FEM Service\" \/>\n<meta property=\"og:description\" content=\"Il numero di febbraio de Il progettista Industriale, dopo la distribuzione agli abbonati nel formato cartaceo, \u00e8 ora online e scaricabile anche dalle app per iOs e Android (in fondo trovate le istruzioni per leggerlo). Vi segnaliamo qualche contenuto che riteniamo particolarmente interessante, a partire dall\u2019articolo intitolato La sfida all\u2019Europa. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/\" \/>\n<meta property=\"og:site_name\" content=\"CFD FEA\/FEM Service\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cfdfeaservice\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-12T02:00:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/02\/PI_2019_002_001.jpg\" \/>\n<meta name=\"author\" content=\"CFD FEA SERVICE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"CFD FEA SERVICE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/\"},\"author\":{\"name\":\"CFD FEA SERVICE\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\"},\"headline\":\"Il numero di febbraio de Il Progettista Industriale \u00e8 online!\",\"datePublished\":\"2019-02-12T02:00:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/\"},\"wordCount\":277,\"publisher\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/02\/PI_2019_002_001.jpg\",\"articleSection\":[\"Normativa\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/\",\"url\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/\",\"name\":\"Il numero di febbraio de Il Progettista Industriale \u00e8 online! - CFD FEA\/FEM Service\",\"isPartOf\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/02\/PI_2019_002_001.jpg\",\"datePublished\":\"2019-02-12T02:00:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/#primaryimage\",\"url\":\"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/02\/PI_2019_002_001.jpg\",\"contentUrl\":\"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/02\/PI_2019_002_001.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cfdfeaservice.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il numero di febbraio de Il Progettista Industriale \u00e8 online!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cfdfeaservice.it\/#website\",\"url\":\"https:\/\/cfdfeaservice.it\/\",\"name\":\"CFD FEA\/FEM Service\",\"description\":\"Servizi di ingegneria 4.0\",\"publisher\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cfdfeaservice.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\",\"name\":\"CFD FEA SERVICE SRL\",\"url\":\"https:\/\/cfdfeaservice.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"contentUrl\":\"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"width\":677,\"height\":178,\"caption\":\"CFD FEA SERVICE SRL\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cfdfeaservice\",\"https:\/\/www.linkedin.com\/company\/11421185\/\",\"https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\",\"name\":\"CFD FEA SERVICE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"caption\":\"CFD FEA SERVICE\"},\"url\":\"https:\/\/cfdfeaservice.it\/index.php\/author\/cfd-fea-service\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il numero di febbraio de Il Progettista Industriale \u00e8 online! - CFD FEA\/FEM Service","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/","og_locale":"en_GB","og_type":"article","og_title":"Il numero di febbraio de Il Progettista Industriale \u00e8 online! - CFD FEA\/FEM Service","og_description":"Il numero di febbraio de Il progettista Industriale, dopo la distribuzione agli abbonati nel formato cartaceo, \u00e8 ora online e scaricabile anche dalle app per iOs e Android (in fondo trovate le istruzioni per leggerlo). Vi segnaliamo qualche contenuto che riteniamo particolarmente interessante, a partire dall\u2019articolo intitolato La sfida all\u2019Europa. [&hellip;]","og_url":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/","og_site_name":"CFD FEA\/FEM Service","article_publisher":"https:\/\/www.facebook.com\/cfdfeaservice","article_published_time":"2019-02-12T02:00:21+00:00","og_image":[{"url":"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/02\/PI_2019_002_001.jpg","type":"","width":"","height":""}],"author":"CFD FEA SERVICE","twitter_card":"summary_large_image","twitter_misc":{"Written by":"CFD FEA SERVICE","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/#article","isPartOf":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/"},"author":{"name":"CFD FEA SERVICE","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7"},"headline":"Il numero di febbraio de Il Progettista Industriale \u00e8 online!","datePublished":"2019-02-12T02:00:21+00:00","mainEntityOfPage":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/"},"wordCount":277,"publisher":{"@id":"https:\/\/cfdfeaservice.it\/#organization"},"image":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/02\/PI_2019_002_001.jpg","articleSection":["Normativa"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/","url":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/","name":"Il numero di febbraio de Il Progettista Industriale \u00e8 online! - CFD FEA\/FEM Service","isPartOf":{"@id":"https:\/\/cfdfeaservice.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/#primaryimage"},"image":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/02\/PI_2019_002_001.jpg","datePublished":"2019-02-12T02:00:21+00:00","breadcrumb":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/#primaryimage","url":"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/02\/PI_2019_002_001.jpg","contentUrl":"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/02\/PI_2019_002_001.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/12\/il-numero-di-febbraio-de-il-progettista-industriale-e-online\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cfdfeaservice.it\/"},{"@type":"ListItem","position":2,"name":"Il numero di febbraio de Il Progettista Industriale \u00e8 online!"}]},{"@type":"WebSite","@id":"https:\/\/cfdfeaservice.it\/#website","url":"https:\/\/cfdfeaservice.it\/","name":"CFD FEA\/FEM Service","description":"Servizi di ingegneria 4.0","publisher":{"@id":"https:\/\/cfdfeaservice.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cfdfeaservice.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cfdfeaservice.it\/#organization","name":"CFD FEA SERVICE SRL","url":"https:\/\/cfdfeaservice.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1","contentUrl":"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1","width":677,"height":178,"caption":"CFD FEA SERVICE SRL"},"image":{"@id":"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cfdfeaservice","https:\/\/www.linkedin.com\/company\/11421185\/","https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA"]},{"@type":"Person","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7","name":"CFD FEA SERVICE","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g","caption":"CFD FEA SERVICE"},"url":"https:\/\/cfdfeaservice.it\/index.php\/author\/cfd-fea-service\/"}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p9JrPq-Dq","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/2444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/comments?post=2444"}],"version-history":[{"count":0,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/2444\/revisions"}],"wp:attachment":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/media?parent=2444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/categories?post=2444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/tags?post=2444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}