{"id":2478,"date":"2019-02-20T03:00:36","date_gmt":"2019-02-20T02:00:36","guid":{"rendered":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/"},"modified":"2019-02-20T03:00:36","modified_gmt":"2019-02-20T02:00:36","slug":"emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali","status":"publish","type":"post","link":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/","title":{"rendered":"Emendamenti edilizia rischiano di compromettere la trasparenza negli affidamenti di incarichi professionali"},"content":{"rendered":"<div>\n<p>\u201cSiamo perplessi e preoccupati per gli effetti di una serie di emendamenti introdotti in Commissione al Senato nella legge di conversione del \u201cDecreto Semplificazioni\u201d; emendamenti che modificano, in seno a provvedimenti omnibus privi di una visione organica, leggi di riferimento in ambiti specifici e fondamentali nei processi di trasformazione del territorio, come il <a href=\"https:\/\/www.unionegeometri.com\/codice-dei-contratti-collaudo-no-degli-ingegneri-al-decreto-attuativo-varato-dal-consiglio-superiore-dei-lavori-pubblici\/\">Codice dei contratti<\/a> ed il <a href=\"https:\/\/www.unionegeometri.com\/approvazione-testo-unico-edilizia-soddisfazione-della-consulta-degli-ordini-degli-architetti-p-p-c-di-sicilia\/\">testo unico dell\u2019edilizia<\/a>, rischiando di compromettere la trasparenza negli affidamenti di incarichi professionali e di mettere in ginocchio il settore delle costruzioni\u201d. Cos\u00ec Giuseppe Cappochin, Presidente del Consiglio Nazionale degli Architetti, Pianificatori, Paesaggisti e Conservatori.<\/p>\n<blockquote>\n<p>\u201cEntrando nel merito \u2013 continua Cappochin \u2013 l\u2019emendamento 5.27 \u00e8 del tutto incomprensibile in quanto vieta alle stazioni appaltanti di ricorrere al cosiddetto Decreto parametri, ma solo per affidamenti diretti di cui all\u2019art.31 comma 8 del Codice. Forse sfugge a chi ha proposto l\u2019emendamento che, in ogni caso, per procedere all\u2019affidamento diretto, le stazioni appaltanti devono prima calcolare l\u2019importo a base di gara con il Decreto parametri, come prescrive l\u2019art.24 comma 8 (che non \u00e8 stato abrogato), e solo dopo possono essere attivate le procedure di affidamento diretto, per le quali il Codice prevede peraltro l\u2019applicazione del criterio di selezione del prezzo pi\u00f9 basso. Non si intuiscono, quindi, le finalit\u00e0 di un emendamento inutile, contraddittorio e pericoloso che produrr\u00e0 solo confusione, errori e contenziosi, finendo per appesantire anzich\u00e9 semplificare gli affidamenti\u201d.<\/p>\n<\/blockquote>\n<p>\u201cAltri emendamenti incomprensibili sono il 5.0.22 e il 7.0.5 che, perseguendo un\u2019illusoria semplificazione nell\u2019ambito del testo unico per l\u2019edilizia, finiscono per complicare notevolmente le procedure per il deposito di progetti strutturali all\u2019Ufficio della Regione (Genio Civile), per tramite dello sportello unico. Infatti, mentre il testo vigente prescrive l\u2019autorizzazione preventiva solo per gli interventi strutturali nelle zone ad alta sismicit\u00e0, per effetto dell\u2019emendamento l\u2019autorizzazione preventiva sarebbe necessaria anche per le nuove costruzioni ricadenti in zona a bassa sismicit\u00e0, se ritenute \u201crilevanti dal punto di vista della pubblica incolumit\u00e0\u201d. Con il risultato di avere appesantito le procedure attualmente adottate dagli addetti ai lavori, attribuendo notevoli responsabilit\u00e0 al professionista incaricato che, in relazione all\u2019intervento progettato, dovr\u00e0 assumere la decisione di procedere al semplice deposito o, al contrario, richiedere l\u2019autorizzazione preventiva\u201d.<\/p>\n<h3>\u201cCi siamo adoperati e ci stiamo adoperando \u2013 conclude Cappochin \u2013 per promuovere modifiche sostanziali o il ritiro degli emendamenti quando verranno esaminati dall\u2019Assemblea del Senato. Nel caso in cui ci\u00f2 non avvenisse valuteremo le forme di protesta da adottare, unitamente alla Rete delle Professioni Tecniche\u201d<\/h3>\n<p>L&#8217;articolo <a rel=\"nofollow\" href=\"https:\/\/www.unioneingegneri.com\/emendamenti-edilizia-mettono-a-rischio-il-settore-delle-costruzioni\/\">Emendamenti edilizia rischiano di compromettere la trasparenza negli affidamenti di incarichi professionali<\/a> proviene da <a rel=\"nofollow\" href=\"https:\/\/www.unioneingegneri.com\/\">Unione Geometri<\/a>.<\/p>\n<\/div>\n<p><a href=\"https:\/\/www.unionearchitetti.com\/emendamenti-edilizia-mettono-a-rischio-il-settore-delle-costruzioni\">Vai alla fonte.<\/a><\/p>\n<p>Autore: Mauro Melis<\/p>\n<p class=\"wpematico_credit\"><small>Powered by <a href=\"http:\/\/www.wpematico.com\" target=\"_blank\">WPeMatico<\/a><\/small><\/p>\n<p><strong>_________________________________<\/strong><\/p>\n<p><strong>CFD FEA Service SRL<\/strong> &egrave; una societ&agrave; di servizi che offre <em>consulenza<\/em> e <em>formazione<\/em> in ambito <strong>ingegneria<\/strong> e <strong>IT<\/strong>. Se questo post\/prodotto ti &egrave; piaciuto ti invitiamo a:<\/p>\n<ul>\n<li>visionare il nostro <a href=\"https:\/\/cfdfeaservice.it\/index.php\/blog\/\" target=\"_blank\" rel=\"noopener\">blog<\/a><\/li>\n<li>visionare i <a href=\"https:\/\/cfdfeaservice.it\/index.php\/prodotti\/\" target=\"_blank\" rel=\"noopener\">software<\/a> disponibili - anche per la formazione<\/li>\n<li>iscriverti alla nostra newsletter<\/li>\n<li>entrare in contatto con noi attraverso la <a href=\"https:\/\/cfdfeaservice.it\/#ribbon\" target=\"_blank\" rel=\"noopener\">pagina contatti<\/a><\/li>\n<\/ul>\n<p>Saremo lieti di seguire le tue richieste e fornire risposte alle tue domande.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u201cSiamo perplessi e preoccupati per gli effetti di una serie di emendamenti introdotti in Commissione al Senato nella legge di conversione del \u201cDecreto Semplificazioni\u201d; emendamenti che modificano, in seno a provvedimenti omnibus privi di una visione organica, leggi di riferimento in ambiti specifici e fondamentali nei processi di trasformazione del [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[57],"tags":[],"class_list":["post-2478","post","type-post","status-publish","format-standard","hentry","category-normativa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emendamenti edilizia rischiano di compromettere la trasparenza negli affidamenti di incarichi professionali - CFD FEA\/FEM Service<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emendamenti edilizia rischiano di compromettere la trasparenza negli affidamenti di incarichi professionali - CFD FEA\/FEM Service\" \/>\n<meta property=\"og:description\" content=\"\u201cSiamo perplessi e preoccupati per gli effetti di una serie di emendamenti introdotti in Commissione al Senato nella legge di conversione del \u201cDecreto Semplificazioni\u201d; emendamenti che modificano, in seno a provvedimenti omnibus privi di una visione organica, leggi di riferimento in ambiti specifici e fondamentali nei processi di trasformazione del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/\" \/>\n<meta property=\"og:site_name\" content=\"CFD FEA\/FEM Service\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cfdfeaservice\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-20T02:00:36+00:00\" \/>\n<meta name=\"author\" content=\"CFD FEA SERVICE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"CFD FEA SERVICE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/\"},\"author\":{\"name\":\"CFD FEA SERVICE\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\"},\"headline\":\"Emendamenti edilizia rischiano di compromettere la trasparenza negli affidamenti di incarichi professionali\",\"datePublished\":\"2019-02-20T02:00:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/\"},\"wordCount\":443,\"publisher\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\"},\"articleSection\":[\"Normativa\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/\",\"url\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/\",\"name\":\"Emendamenti edilizia rischiano di compromettere la trasparenza negli affidamenti di incarichi professionali - CFD FEA\/FEM Service\",\"isPartOf\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#website\"},\"datePublished\":\"2019-02-20T02:00:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cfdfeaservice.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emendamenti edilizia rischiano di compromettere la trasparenza negli affidamenti di incarichi professionali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cfdfeaservice.it\/#website\",\"url\":\"https:\/\/cfdfeaservice.it\/\",\"name\":\"CFD FEA\/FEM Service\",\"description\":\"Servizi di ingegneria 4.0\",\"publisher\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cfdfeaservice.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\",\"name\":\"CFD FEA SERVICE SRL\",\"url\":\"https:\/\/cfdfeaservice.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"contentUrl\":\"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"width\":677,\"height\":178,\"caption\":\"CFD FEA SERVICE SRL\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cfdfeaservice\",\"https:\/\/www.linkedin.com\/company\/11421185\/\",\"https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\",\"name\":\"CFD FEA SERVICE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"caption\":\"CFD FEA SERVICE\"},\"url\":\"https:\/\/cfdfeaservice.it\/index.php\/author\/cfd-fea-service\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emendamenti edilizia rischiano di compromettere la trasparenza negli affidamenti di incarichi professionali - CFD FEA\/FEM Service","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/","og_locale":"en_GB","og_type":"article","og_title":"Emendamenti edilizia rischiano di compromettere la trasparenza negli affidamenti di incarichi professionali - CFD FEA\/FEM Service","og_description":"\u201cSiamo perplessi e preoccupati per gli effetti di una serie di emendamenti introdotti in Commissione al Senato nella legge di conversione del \u201cDecreto Semplificazioni\u201d; emendamenti che modificano, in seno a provvedimenti omnibus privi di una visione organica, leggi di riferimento in ambiti specifici e fondamentali nei processi di trasformazione del [&hellip;]","og_url":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/","og_site_name":"CFD FEA\/FEM Service","article_publisher":"https:\/\/www.facebook.com\/cfdfeaservice","article_published_time":"2019-02-20T02:00:36+00:00","author":"CFD FEA SERVICE","twitter_card":"summary_large_image","twitter_misc":{"Written by":"CFD FEA SERVICE","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/#article","isPartOf":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/"},"author":{"name":"CFD FEA SERVICE","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7"},"headline":"Emendamenti edilizia rischiano di compromettere la trasparenza negli affidamenti di incarichi professionali","datePublished":"2019-02-20T02:00:36+00:00","mainEntityOfPage":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/"},"wordCount":443,"publisher":{"@id":"https:\/\/cfdfeaservice.it\/#organization"},"articleSection":["Normativa"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/","url":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/","name":"Emendamenti edilizia rischiano di compromettere la trasparenza negli affidamenti di incarichi professionali - CFD FEA\/FEM Service","isPartOf":{"@id":"https:\/\/cfdfeaservice.it\/#website"},"datePublished":"2019-02-20T02:00:36+00:00","breadcrumb":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/20\/emendamenti-edilizia-rischiano-di-compromettere-la-trasparenza-negli-affidamenti-di-incarichi-professionali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cfdfeaservice.it\/"},{"@type":"ListItem","position":2,"name":"Emendamenti edilizia rischiano di compromettere la trasparenza negli affidamenti di incarichi professionali"}]},{"@type":"WebSite","@id":"https:\/\/cfdfeaservice.it\/#website","url":"https:\/\/cfdfeaservice.it\/","name":"CFD FEA\/FEM Service","description":"Servizi di ingegneria 4.0","publisher":{"@id":"https:\/\/cfdfeaservice.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cfdfeaservice.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cfdfeaservice.it\/#organization","name":"CFD FEA SERVICE SRL","url":"https:\/\/cfdfeaservice.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1","contentUrl":"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1","width":677,"height":178,"caption":"CFD FEA SERVICE SRL"},"image":{"@id":"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cfdfeaservice","https:\/\/www.linkedin.com\/company\/11421185\/","https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA"]},{"@type":"Person","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7","name":"CFD FEA SERVICE","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g","caption":"CFD FEA SERVICE"},"url":"https:\/\/cfdfeaservice.it\/index.php\/author\/cfd-fea-service\/"}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p9JrPq-DY","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/2478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/comments?post=2478"}],"version-history":[{"count":0,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/2478\/revisions"}],"wp:attachment":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/media?parent=2478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/categories?post=2478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/tags?post=2478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}