{"id":2506,"date":"2019-02-26T03:00:49","date_gmt":"2019-02-26T02:00:49","guid":{"rendered":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/"},"modified":"2019-02-26T03:00:49","modified_gmt":"2019-02-26T02:00:49","slug":"e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio","status":"publish","type":"post","link":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/","title":{"rendered":"E-fatture pi\u00f9 che raddoppiate nei primi 18 giorni di febbraio"},"content":{"rendered":"<div>\n<p>Al 18 febbraio inviate 230 milioni di e-fatture da parte di 2,3 milioni di operatori: pi\u00f9 che raddoppiati gli invii di gennaio. Lombardia prima con oltre 80 milioni di fatture elettroniche trasmesse.<\/p>\n<blockquote>\n<p>E-fatture pi\u00f9 che raddoppiate nei primi 18 giorni di febbraio. I dati alle ore 9 di ieri, ultimo giorno per l\u2019invio da parte dei contribuenti mensili delle fatture relative alle operazioni effettuate a gennaio, mostrano un trend in forte ascesa con 228 milioni di file inviati da parte di oltre 2,3 milioni di operatori. Con gli invii del solo mese di febbraio \u00e8 dunque pi\u00f9 che raddoppiato il numero di fatture transitate per il Sistema di interscambio (Sdi) dell\u2019Agenzia, gestito dal partner tecnologico Sogei: al 31 gennaio, infatti, erano circa 100 milioni le fatture inviate da parte di un milione e mezzo di operatori. Nella classifica delle regioni svetta la Lombardia con oltre 80 milioni di invii, mentre tra i comparti spicca quello del commercio e riparazione di autoveicoli e motocicli.<\/p>\n<\/blockquote>\n<p><a href=\"https:\/\/www.unionegeometri.com\/fattura-elettronica-in-vigore-per-il-subappalto-e-subcontraenti-di-un-contratto-di-appalto-pubblico\/\"><strong>Tutti i numeri dell\u2019e-fattura<\/strong><\/a> \u2013 Dal 1\u00b0 gennaio 2019, data di entrata in vigore dell\u2019obbligo generalizzato di <strong>fatturazione elettronica<\/strong>, sono stati inviati 228 milioni di file da parte di 2,3 milioni di soggetti: in pratica, circa 100 e-fatture a operatore. Il 4,43% degli invii non \u00e8 andato a buon fine per errori nella compilazione, come indicazione di partita Iva errata, codice destinatario errato, fattura duplicata, errore nell\u2019estensione del file, due o pi\u00f9 fatture con lo stesso nome. In totale, sono state rilasciate 7 milioni di deleghe per i servizi del sistema Fatture e corrispettivi, di cui 2 milioni tramite gli uffici delle Entrate e 5 milioni attraverso le altre modalit\u00e0 (<em>area riservata del sito internet delle Entrate, pec<\/em>) .<\/p>\n<h3>A quota 3,6 milioni, invece, le registrazioni dell\u2019indirizzo telematico: si tratta del servizio che consente agli utenti di registrare l\u2019indirizzo pec o il codice destinatario di 7 cifre al quale lo Sdi indirizza in maniera automatica tutte le fatture elettroniche. Sono 3,3 milioni, infine, le richieste di generazione del Qr code da mostrare al fornitore tramite smartphone, tablet o su carta, per consentirgli di acquisire in automatico i dati del cliente.<\/h3>\n<blockquote>\n<p>Le e-fatture per attivit\u00e0 \u2013 Il settore pi\u00f9 interessato dalla trasmissione delle fatture elettroniche \u00e8 quello del commercio all\u2019ingrosso e al dettaglio-riparazione di autoveicoli e motocicli, che fa registrare, sempre al 18 febbraio, 55.750.194 invii da parte di 550.039 operatori. Nel settore delle manifatture sono oltre 20 milioni le fatture trasmesse (20.236.052), mentre superano la soglia dei 10 milioni i file inviati da parte di attivit\u00e0 di noleggio, agenzie di viaggio e servizi di supporto alle imprese (10.490.684) e toccano quota 7,7 milioni quelli inviati nel settore del trasporto e magazzinaggio (7.741.565). Con riguardo invece alla platea degli operatori coinvolti, tra i pi\u00f9 attivi, dopo concessionarie e autofficine, troviamo liberi professionisti (338.691), costruttori (269.972), manifatture (269.600), agenti immobiliari (142.627), alberghi e ristoranti (121.171).<\/p>\n<\/blockquote>\n<p>La Lombardia guida la classifica regionale \u2013 Lombardia prima in classifica per numero di fatture trasmesse, con oltre 80 milioni di invii (81.180.119), seguita dal Lazio (51.235.686 invii), e dall\u2019Emilia-Romagna (13.524.740). Tra le regioni del Nord bene anche Veneto (12.153.873 invii) e Piemonte (12.009.929). L\u2019Italia centrale vede la Toscana superare la soglia di 8 milioni di fatture inviate (8.048.074), seguita dalle Marche (3.103.146) e dall\u2019Umbria (1.792.741). Al Sud la Campania fa registrare quasi 7 milioni di invii (6.947.742), la Sicilia raggiunge quota 4.696.895, mentre in Puglia sono 4.344.587 le fatture inviate al sistema.<\/p>\n<p>L&#8217;articolo <a rel=\"nofollow\" href=\"https:\/\/www.unioneingegneri.com\/e-fatture-raddoppiate-nei-primi-18-giorni-di-febbraio-le-fatture-elettroniche\/\">E-fatture pi\u00f9 che raddoppiate nei primi 18 giorni di febbraio<\/a> proviene da <a rel=\"nofollow\" href=\"https:\/\/www.unioneingegneri.com\/\">Unione Geometri<\/a>.<\/p>\n<\/div>\n<p><a href=\"https:\/\/www.unionegeometri.com\/e-fatture-raddoppiate-nei-primi-18-giorni-di-febbraio-le-fatture-elettroniche\">Vai alla fonte.<\/a><\/p>\n<p>Autore: Mauro Melis<\/p>\n<p class=\"wpematico_credit\"><small>Powered by <a href=\"http:\/\/www.wpematico.com\" target=\"_blank\" rel=\"noopener noreferrer\">WPeMatico<\/a><\/small><\/p>\n<p><strong>_________________________________<\/strong><\/p>\n<p><strong>CFD FEA Service SRL<\/strong> &egrave; una societ&agrave; di servizi che offre <em>consulenza<\/em> e <em>formazione<\/em> in ambito <strong>ingegneria<\/strong> e <strong>IT<\/strong>. Se questo post\/prodotto ti &egrave; piaciuto ti invitiamo a:<\/p>\n<ul>\n<li>visionare il nostro <a href=\"https:\/\/cfdfeaservice.it\/index.php\/blog\/\" target=\"_blank\" rel=\"noopener\">blog<\/a><\/li>\n<li>visionare i <a href=\"https:\/\/cfdfeaservice.it\/index.php\/prodotti\/\" target=\"_blank\" rel=\"noopener\">software<\/a> disponibili - anche per la formazione<\/li>\n<li>iscriverti alla nostra newsletter<\/li>\n<li>entrare in contatto con noi attraverso la <a href=\"https:\/\/cfdfeaservice.it\/#ribbon\" target=\"_blank\" rel=\"noopener\">pagina contatti<\/a><\/li>\n<\/ul>\n<p>Saremo lieti di seguire le tue richieste e fornire risposte alle tue domande.<\/p>","protected":false},"excerpt":{"rendered":"<p>Al 18 febbraio inviate 230 milioni di e-fatture da parte di 2,3 milioni di operatori: pi\u00f9 che raddoppiati gli invii di gennaio. Lombardia prima con oltre 80 milioni di fatture elettroniche trasmesse. E-fatture pi\u00f9 che raddoppiate nei primi 18 giorni di febbraio. I dati alle ore 9 di ieri, ultimo [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[57],"tags":[],"class_list":["post-2506","post","type-post","status-publish","format-standard","hentry","category-normativa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>E-fatture pi\u00f9 che raddoppiate nei primi 18 giorni di febbraio - CFD FEA\/FEM Service<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"E-fatture pi\u00f9 che raddoppiate nei primi 18 giorni di febbraio - CFD FEA\/FEM Service\" \/>\n<meta property=\"og:description\" content=\"Al 18 febbraio inviate 230 milioni di e-fatture da parte di 2,3 milioni di operatori: pi\u00f9 che raddoppiati gli invii di gennaio. Lombardia prima con oltre 80 milioni di fatture elettroniche trasmesse. E-fatture pi\u00f9 che raddoppiate nei primi 18 giorni di febbraio. I dati alle ore 9 di ieri, ultimo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/\" \/>\n<meta property=\"og:site_name\" content=\"CFD FEA\/FEM Service\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cfdfeaservice\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-26T02:00:49+00:00\" \/>\n<meta name=\"author\" content=\"CFD FEA SERVICE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"CFD FEA SERVICE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/\"},\"author\":{\"name\":\"CFD FEA SERVICE\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\"},\"headline\":\"E-fatture pi\u00f9 che raddoppiate nei primi 18 giorni di febbraio\",\"datePublished\":\"2019-02-26T02:00:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/\"},\"wordCount\":555,\"publisher\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\"},\"articleSection\":[\"Normativa\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/\",\"url\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/\",\"name\":\"E-fatture pi\u00f9 che raddoppiate nei primi 18 giorni di febbraio - CFD FEA\/FEM Service\",\"isPartOf\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#website\"},\"datePublished\":\"2019-02-26T02:00:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cfdfeaservice.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E-fatture pi\u00f9 che raddoppiate nei primi 18 giorni di febbraio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cfdfeaservice.it\/#website\",\"url\":\"https:\/\/cfdfeaservice.it\/\",\"name\":\"CFD FEA\/FEM Service\",\"description\":\"Servizi di ingegneria 4.0\",\"publisher\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cfdfeaservice.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\",\"name\":\"CFD FEA SERVICE SRL\",\"url\":\"https:\/\/cfdfeaservice.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"contentUrl\":\"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"width\":677,\"height\":178,\"caption\":\"CFD FEA SERVICE SRL\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cfdfeaservice\",\"https:\/\/www.linkedin.com\/company\/11421185\/\",\"https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\",\"name\":\"CFD FEA SERVICE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"caption\":\"CFD FEA SERVICE\"},\"url\":\"https:\/\/cfdfeaservice.it\/index.php\/author\/cfd-fea-service\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"E-fatture pi\u00f9 che raddoppiate nei primi 18 giorni di febbraio - CFD FEA\/FEM Service","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/","og_locale":"en_GB","og_type":"article","og_title":"E-fatture pi\u00f9 che raddoppiate nei primi 18 giorni di febbraio - CFD FEA\/FEM Service","og_description":"Al 18 febbraio inviate 230 milioni di e-fatture da parte di 2,3 milioni di operatori: pi\u00f9 che raddoppiati gli invii di gennaio. Lombardia prima con oltre 80 milioni di fatture elettroniche trasmesse. E-fatture pi\u00f9 che raddoppiate nei primi 18 giorni di febbraio. I dati alle ore 9 di ieri, ultimo [&hellip;]","og_url":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/","og_site_name":"CFD FEA\/FEM Service","article_publisher":"https:\/\/www.facebook.com\/cfdfeaservice","article_published_time":"2019-02-26T02:00:49+00:00","author":"CFD FEA SERVICE","twitter_card":"summary_large_image","twitter_misc":{"Written by":"CFD FEA SERVICE","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/#article","isPartOf":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/"},"author":{"name":"CFD FEA SERVICE","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7"},"headline":"E-fatture pi\u00f9 che raddoppiate nei primi 18 giorni di febbraio","datePublished":"2019-02-26T02:00:49+00:00","mainEntityOfPage":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/"},"wordCount":555,"publisher":{"@id":"https:\/\/cfdfeaservice.it\/#organization"},"articleSection":["Normativa"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/","url":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/","name":"E-fatture pi\u00f9 che raddoppiate nei primi 18 giorni di febbraio - CFD FEA\/FEM Service","isPartOf":{"@id":"https:\/\/cfdfeaservice.it\/#website"},"datePublished":"2019-02-26T02:00:49+00:00","breadcrumb":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/02\/26\/e-fatture-piu-che-raddoppiate-nei-primi-18-giorni-di-febbraio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cfdfeaservice.it\/"},{"@type":"ListItem","position":2,"name":"E-fatture pi\u00f9 che raddoppiate nei primi 18 giorni di febbraio"}]},{"@type":"WebSite","@id":"https:\/\/cfdfeaservice.it\/#website","url":"https:\/\/cfdfeaservice.it\/","name":"CFD FEA\/FEM Service","description":"Servizi di ingegneria 4.0","publisher":{"@id":"https:\/\/cfdfeaservice.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cfdfeaservice.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cfdfeaservice.it\/#organization","name":"CFD FEA SERVICE SRL","url":"https:\/\/cfdfeaservice.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1","contentUrl":"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1","width":677,"height":178,"caption":"CFD FEA SERVICE SRL"},"image":{"@id":"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cfdfeaservice","https:\/\/www.linkedin.com\/company\/11421185\/","https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA"]},{"@type":"Person","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7","name":"CFD FEA SERVICE","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g","caption":"CFD FEA SERVICE"},"url":"https:\/\/cfdfeaservice.it\/index.php\/author\/cfd-fea-service\/"}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p9JrPq-Eq","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/2506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/comments?post=2506"}],"version-history":[{"count":0,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/2506\/revisions"}],"wp:attachment":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/media?parent=2506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/categories?post=2506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/tags?post=2506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}