{"id":2524,"date":"2019-03-01T03:01:04","date_gmt":"2019-03-01T02:01:04","guid":{"rendered":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/"},"modified":"2019-03-01T03:01:04","modified_gmt":"2019-03-01T02:01:04","slug":"affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019","status":"publish","type":"post","link":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/","title":{"rendered":"Affidamenti diretti nei lavori: circolare CNI su Legge di bilancio 2019 e Linee guida Anac n. 4\/2019"},"content":{"rendered":"<div>\n<p>Con la Circolare n. 352 \/XIX Sess. del 25 febbraio 2019, il Consiglio nazionale degli Ingegneri ricorda che la Legge 30 dicembre 2018, n. 145 recante \u201cbilancio di previsione dello Stato per l\u2019anno finanziario 2019 e bilancio pluriennale per il triennio 2019-2021\u201d \u2013 pubblicata nella Gazzetta Ufficiale il 31 dicembre 2018 (n. 302, S.O.) ed entrata in vigore il 1\u00b0 gennaio 2019 (ad eccezione di alcune disposizioni che sono entrate in vigore il 31 dicembre 2018) \u2013 ha provveduto a modificare il Codice dei Contratti (il gi\u00e0 novellato D.Lgs. n. 50 del 2016), nelle more di una sua complessiva revisione.<\/p>\n<h3>In particolare, nel settore dei lavori, la Legge di Bilancio 2019 (art. 1 comma 912) ha previsto l\u2019innalzamento della soglia per l\u2019affidamento diretto per importi pari o superiori a \u20ac 40.000 ed inferiori a \u20ac 150.000, \u201cprevia consultazione di almeno 3 operatori economici\u201d nonch\u00e9 l\u2019innalzamento della soglia della procedura negoziata con almeno dieci operatori economici, per importi pari o superiori a \u20ac 150.000 ed inferiori a \u20ac 350.000 (art. 36, comma 2, lett. b).<\/h3>\n<blockquote>\n<p>Invece, per quanto attiene i servizi e le forniture resta tutto invariato e, quindi per gli stessi \u00e8 possibile continuare ad applicare l\u2019articolo 36, comma 2, lettere a) e b) dell\u2019attuale testo del Codice dei Contratti di cui al D.lgs. n. 50\/2016 con affidamenti diretti per importi sino a 40.000 euro (lettera a)) e con procedura negoziata (lettera b)) per importi sino alla soglia comunitaria, fermo restando all\u2019interno dei servizi la specificit\u00e0 dei servizi di Ingegneria e Architettura di cui agli articoli 31 comma 8, 157 comma 2 e 95 comma 3.<\/p>\n<\/blockquote>\n<h3>Le modifiche alla normativa, la cui operativit\u00e0 temporale \u00e8 comunque stata limitata al 31 dicembre 2019, appaiono concepite nell\u2019ottica di dotare le Stazioni appaltanti di una maggiore discrezionalit\u00e0.<\/h3>\n<p>A tale riguardo l\u2019ANAC, con le Linee Guida n. 4 di attuazione del Decreto Legislativo 18 aprile 2016, n. 50, recanti \u201cProcedure per l\u2019affidamento dei contratti pubblici di importo inferiore alle soglie di rilevanza comunitaria, indagini di mercato e formazione e gestione degli elenchi di operatori economici\u201d, ha recentemente pubblicato e sottoposto a consultazione pubblica una proposta di modifica sugli appalti sotto la soglia comunitaria.<\/p>\n<h3>L\u2019ANAC ha specificato e confermato che l\u2019affidamento diretto previa consultazione di 3 operatori, tra \u20ac 40.000 e \u20ac 150.000 (in luogo della procedura negoziata con 10 invitati), coinvolge il solo settore dei lavori e non anche quello dei servizi di ingegneria e architettura come da alcuni erroneamente paventato.<\/h3>\n<p>Sul punto l\u2019Autorit\u00e0 propone di inserire nelle Linee guida un riferimento al periodo transitorio introdotto dalla norma, specificando che per l\u2019anno 2019, per gli affidamenti di lavori, valgono le soglie introdotte dalla legge 145\/2018. Inoltre, secondo l\u2019ANAC si ritiene utile chiarire il significato da attribuire alla locuzione \u00abaffidamento diretto previa consultazione di tre operatori\u00bb, atteso che in tale espressione sono accostati termini che connotano due procedure diverse: l\u2019affidamento diretto e la procedura negoziata.<\/p>\n<p>L&#8217;articolo <a rel=\"nofollow\" href=\"https:\/\/www.unioneingegneri.com\/circolare-del-cni-sugli-affidamenti-diretti-nei-lavori-pubblici\/\">Affidamenti diretti nei lavori: circolare CNI su Legge di bilancio 2019 e Linee guida Anac n. 4\/2019<\/a> proviene da <a rel=\"nofollow\" href=\"https:\/\/www.unioneingegneri.com\/\">Unione Geometri<\/a>.<\/p>\n<\/div>\n<p><a href=\"https:\/\/www.unioneingegneri.com\/circolare-del-cni-sugli-affidamenti-diretti-nei-lavori-pubblici\/\">Vai alla fonte.<\/a><\/p>\n<p>Autore: Redazione<\/p>\n<p class=\"wpematico_credit\"><small>Powered by <a href=\"http:\/\/www.wpematico.com\" target=\"_blank\" rel=\"noopener noreferrer\">WPeMatico<\/a><\/small><\/p>\n<p><strong>_________________________________<\/strong><\/p>\n<p><strong>CFD FEA Service SRL<\/strong> &egrave; una societ&agrave; di servizi che offre <em>consulenza<\/em> e <em>formazione<\/em> in ambito <strong>ingegneria<\/strong> e <strong>IT<\/strong>. Se questo post\/prodotto ti &egrave; piaciuto ti invitiamo a:<\/p>\n<ul>\n<li>visionare il nostro <a href=\"https:\/\/cfdfeaservice.it\/index.php\/blog\/\" target=\"_blank\" rel=\"noopener\">blog<\/a><\/li>\n<li>visionare i <a href=\"https:\/\/cfdfeaservice.it\/index.php\/prodotti\/\" target=\"_blank\" rel=\"noopener\">software<\/a> disponibili - anche per la formazione<\/li>\n<li>iscriverti alla nostra newsletter<\/li>\n<li>entrare in contatto con noi attraverso la <a href=\"https:\/\/cfdfeaservice.it\/#ribbon\" target=\"_blank\" rel=\"noopener\">pagina contatti<\/a><\/li>\n<\/ul>\n<p>Saremo lieti di seguire le tue richieste e fornire risposte alle tue domande.<\/p>","protected":false},"excerpt":{"rendered":"<p>Con la Circolare n. 352 \/XIX Sess. del 25 febbraio 2019, il Consiglio nazionale degli Ingegneri ricorda che la Legge 30 dicembre 2018, n. 145 recante \u201cbilancio di previsione dello Stato per l\u2019anno finanziario 2019 e bilancio pluriennale per il triennio 2019-2021\u201d \u2013 pubblicata nella Gazzetta Ufficiale il 31 dicembre [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[57],"tags":[],"class_list":["post-2524","post","type-post","status-publish","format-standard","hentry","category-normativa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Affidamenti diretti nei lavori: circolare CNI su Legge di bilancio 2019 e Linee guida Anac n. 4\/2019 - CFD FEA\/FEM Service<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Affidamenti diretti nei lavori: circolare CNI su Legge di bilancio 2019 e Linee guida Anac n. 4\/2019 - CFD FEA\/FEM Service\" \/>\n<meta property=\"og:description\" content=\"Con la Circolare n. 352 \/XIX Sess. del 25 febbraio 2019, il Consiglio nazionale degli Ingegneri ricorda che la Legge 30 dicembre 2018, n. 145 recante \u201cbilancio di previsione dello Stato per l\u2019anno finanziario 2019 e bilancio pluriennale per il triennio 2019-2021\u201d \u2013 pubblicata nella Gazzetta Ufficiale il 31 dicembre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"CFD FEA\/FEM Service\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cfdfeaservice\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-01T02:01:04+00:00\" \/>\n<meta name=\"author\" content=\"CFD FEA SERVICE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"CFD FEA SERVICE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/\"},\"author\":{\"name\":\"CFD FEA SERVICE\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\"},\"headline\":\"Affidamenti diretti nei lavori: circolare CNI su Legge di bilancio 2019 e Linee guida Anac n. 4\/2019\",\"datePublished\":\"2019-03-01T02:01:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/\"},\"wordCount\":485,\"publisher\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\"},\"articleSection\":[\"Normativa\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/\",\"url\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/\",\"name\":\"Affidamenti diretti nei lavori: circolare CNI su Legge di bilancio 2019 e Linee guida Anac n. 4\/2019 - CFD FEA\/FEM Service\",\"isPartOf\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#website\"},\"datePublished\":\"2019-03-01T02:01:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cfdfeaservice.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Affidamenti diretti nei lavori: circolare CNI su Legge di bilancio 2019 e Linee guida Anac n. 4\/2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cfdfeaservice.it\/#website\",\"url\":\"https:\/\/cfdfeaservice.it\/\",\"name\":\"CFD FEA\/FEM Service\",\"description\":\"Servizi di ingegneria 4.0\",\"publisher\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cfdfeaservice.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\",\"name\":\"CFD FEA SERVICE SRL\",\"url\":\"https:\/\/cfdfeaservice.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"contentUrl\":\"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"width\":677,\"height\":178,\"caption\":\"CFD FEA SERVICE SRL\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cfdfeaservice\",\"https:\/\/www.linkedin.com\/company\/11421185\/\",\"https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\",\"name\":\"CFD FEA SERVICE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"caption\":\"CFD FEA SERVICE\"},\"url\":\"https:\/\/cfdfeaservice.it\/index.php\/author\/cfd-fea-service\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Affidamenti diretti nei lavori: circolare CNI su Legge di bilancio 2019 e Linee guida Anac n. 4\/2019 - CFD FEA\/FEM Service","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/","og_locale":"en_GB","og_type":"article","og_title":"Affidamenti diretti nei lavori: circolare CNI su Legge di bilancio 2019 e Linee guida Anac n. 4\/2019 - CFD FEA\/FEM Service","og_description":"Con la Circolare n. 352 \/XIX Sess. del 25 febbraio 2019, il Consiglio nazionale degli Ingegneri ricorda che la Legge 30 dicembre 2018, n. 145 recante \u201cbilancio di previsione dello Stato per l\u2019anno finanziario 2019 e bilancio pluriennale per il triennio 2019-2021\u201d \u2013 pubblicata nella Gazzetta Ufficiale il 31 dicembre [&hellip;]","og_url":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/","og_site_name":"CFD FEA\/FEM Service","article_publisher":"https:\/\/www.facebook.com\/cfdfeaservice","article_published_time":"2019-03-01T02:01:04+00:00","author":"CFD FEA SERVICE","twitter_card":"summary_large_image","twitter_misc":{"Written by":"CFD FEA SERVICE","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/#article","isPartOf":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/"},"author":{"name":"CFD FEA SERVICE","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7"},"headline":"Affidamenti diretti nei lavori: circolare CNI su Legge di bilancio 2019 e Linee guida Anac n. 4\/2019","datePublished":"2019-03-01T02:01:04+00:00","mainEntityOfPage":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/"},"wordCount":485,"publisher":{"@id":"https:\/\/cfdfeaservice.it\/#organization"},"articleSection":["Normativa"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/","url":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/","name":"Affidamenti diretti nei lavori: circolare CNI su Legge di bilancio 2019 e Linee guida Anac n. 4\/2019 - CFD FEA\/FEM Service","isPartOf":{"@id":"https:\/\/cfdfeaservice.it\/#website"},"datePublished":"2019-03-01T02:01:04+00:00","breadcrumb":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/01\/affidamenti-diretti-nei-lavori-circolare-cni-su-legge-di-bilancio-2019-e-linee-guida-anac-n-4-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cfdfeaservice.it\/"},{"@type":"ListItem","position":2,"name":"Affidamenti diretti nei lavori: circolare CNI su Legge di bilancio 2019 e Linee guida Anac n. 4\/2019"}]},{"@type":"WebSite","@id":"https:\/\/cfdfeaservice.it\/#website","url":"https:\/\/cfdfeaservice.it\/","name":"CFD FEA\/FEM Service","description":"Servizi di ingegneria 4.0","publisher":{"@id":"https:\/\/cfdfeaservice.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cfdfeaservice.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cfdfeaservice.it\/#organization","name":"CFD FEA SERVICE SRL","url":"https:\/\/cfdfeaservice.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1","contentUrl":"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1","width":677,"height":178,"caption":"CFD FEA SERVICE SRL"},"image":{"@id":"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cfdfeaservice","https:\/\/www.linkedin.com\/company\/11421185\/","https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA"]},{"@type":"Person","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7","name":"CFD FEA SERVICE","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g","caption":"CFD FEA SERVICE"},"url":"https:\/\/cfdfeaservice.it\/index.php\/author\/cfd-fea-service\/"}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p9JrPq-EI","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/2524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/comments?post=2524"}],"version-history":[{"count":0,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/2524\/revisions"}],"wp:attachment":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/media?parent=2524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/categories?post=2524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/tags?post=2524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}