{"id":2580,"date":"2019-03-12T03:03:54","date_gmt":"2019-03-12T02:03:54","guid":{"rendered":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/"},"modified":"2019-03-12T03:03:54","modified_gmt":"2019-03-12T02:03:54","slug":"ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra","status":"publish","type":"post","link":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/","title":{"rendered":"Ogni OPERA ha la cornice che si merita, come ogni finestra!"},"content":{"rendered":"<div>\n<p class=\"p1\"><span class=\"s1\">In un\u2019ottica di continua attenzione ai dettagli e alla qualit\u00e0 dei prodotti forniti, <strong>De Faveri<\/strong> ha incluso nella sua proposta, per delle case che sappiano distinguersi sia per design che per le ottime <strong>performance energetiche e di isolamento termico<\/strong>, il <strong>profilo InOpera<\/strong>.<\/span><\/p>\n<h3 class=\"p1\"><span class=\"s2\">Sistema monoblocco con profilo InOpera<\/span><\/h3>\n<p class=\"p2\"><span class=\"s1\">InOpera permette di allineare la finestra alla muratura, al fine di dare continuit\u00e0 alla parete e non creare rilievi sulla stessa, con la possibilit\u00e0, inoltre, di distanziare il coprifilo per creare una cava di dimensioni variabili tra coprifilo e muro, che pu\u00f2 essere, a piacimento, dipinta come la muratura o con colori diversi.<\/span><\/p>\n<h3 class=\"p2\"><span class=\"s1\">Il profilo viene fornito in barre e va applicato in abbinamento ai monoblocchi.<\/span><\/h3>\n<p class=\"p2\"><span class=\"s1\">Tra le soluzioni monoblocco, che rivestono completamente il foro finestra per garantire il completo isolamento, c\u2019\u00e8 il sistema <strong>InQuadra.<\/strong><\/span><\/p>\n<h3 class=\"p2\"><span class=\"s2\">Sistema InQuadra<\/span><\/h3>\n<blockquote>\n<p class=\"p2\"><span class=\"s1\">La soluzione INQUADRA monoblocco per infissi \u00e8 stata progettata per eliminare i ponti termici del foro finestra, qualsiasi sia il tipo di oscurante si voglia installare, con predisposizione dell\u2019infisso posizionato a filo o centro mazzetta. INQUADRA si differenzia dalle altre soluzioni per la forma regolare che facilita la realizzazione del foro edile. La superficie a vista \u00e8 pronta per la rasatura, da effettuare in cantiere, cos\u00ec da uniformarla in modo omogeneo al resto del cappotto.<\/span><\/p>\n<\/blockquote>\n<h3 class=\"p2\"><span class=\"s1\">INQUADRA \u00e8 formata da un corpo in EPS lambda 0,035 W\/m<\/span><span class=\"s3\"><sup>2<\/sup><\/span><span class=\"s1\">K e spessore 100 mm, da un profilo in PVC progettato per accogliere la guarnizione auto espandente ed una rete per evitare le microcavillature.<\/span><\/h3>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15286 size-full\" src=\"https:\/\/i0.wp.com\/www.unionegeometri.com\/wp-content\/uploads\/2019\/03\/INQUADRA-860X430-1.jpg?resize=750%2C375&#038;ssl=1\" alt=\"InOpera: ogni OPERA ha la cornice che si merita!\" width=\"750\" height=\"375\" srcset=\"https:\/\/www.unioneingegneri.com\/wp-content\/uploads\/2019\/03\/INQUADRA-860X430-1.jpg 860w, https:\/\/www.unioneingegneri.com\/wp-content\/uploads\/2019\/03\/INQUADRA-860X430-1-300x150.jpg 300w, https:\/\/www.unioneingegneri.com\/wp-content\/uploads\/2019\/03\/INQUADRA-860X430-1-768x384.jpg 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\"><\/p>\n<p class=\"p5\"><span class=\"s4\">A completamento della soluzione, il 4\u00b0 lato, realizzato <\/span><span class=\"s1\">con corpo in EPS, ad alta densit\u00e0, spessore 40mm, bordo sagomato per il filo intonaco e bordi coibentati ai lati (a vaschetta), va ad accogliere la soglia o davanzale ed annulla il ponte termico.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Il sistema, inoltre, \u00e8 abbinabile a diverse tipologie di sistema oscurante: cassonetti per avvolgibili, frangisole e per tenda tecnica.<\/span><\/p>\n<p>L&#8217;articolo <a rel=\"nofollow\" href=\"https:\/\/www.unioneingegneri.com\/inopera-ogni-opera-ha-la-cornice-che-si-merita\/\">Ogni OPERA ha la cornice che si merita, come ogni finestra!<\/a> proviene da <a rel=\"nofollow\" href=\"https:\/\/www.unioneingegneri.com\/\">Unione Geometri<\/a>.<\/p>\n<\/div>\n<p><a href=\"https:\/\/www.unionearchitetti.com\/inopera-ogni-opera-ha-la-cornice-che-si-merita\">Vai alla fonte.<\/a><\/p>\n<p>Autore: Mauro Melis<\/p>\n<p class=\"wpematico_credit\"><small>Powered by <a href=\"http:\/\/www.wpematico.com\" target=\"_blank\" rel=\"noopener noreferrer\">WPeMatico<\/a><\/small><\/p>\n<p><strong>_________________________________<\/strong><\/p>\n<p><strong>CFD FEA Service SRL<\/strong> &egrave; una societ&agrave; di servizi che offre <em>consulenza<\/em> e <em>formazione<\/em> in ambito <strong>ingegneria<\/strong> e <strong>IT<\/strong>. Se questo post\/prodotto ti &egrave; piaciuto ti invitiamo a:<\/p>\n<ul>\n<li>visionare il nostro <a href=\"https:\/\/cfdfeaservice.it\/index.php\/blog\/\" target=\"_blank\" rel=\"noopener\">blog<\/a><\/li>\n<li>visionare i <a href=\"https:\/\/cfdfeaservice.it\/index.php\/prodotti\/\" target=\"_blank\" rel=\"noopener\">software<\/a> disponibili - anche per la formazione<\/li>\n<li>iscriverti alla nostra newsletter<\/li>\n<li>entrare in contatto con noi attraverso la <a href=\"https:\/\/cfdfeaservice.it\/#ribbon\" target=\"_blank\" rel=\"noopener\">pagina contatti<\/a><\/li>\n<\/ul>\n<p>Saremo lieti di seguire le tue richieste e fornire risposte alle tue domande.<\/p>","protected":false},"excerpt":{"rendered":"<p>In un\u2019ottica di continua attenzione ai dettagli e alla qualit\u00e0 dei prodotti forniti, De Faveri ha incluso nella sua proposta, per delle case che sappiano distinguersi sia per design che per le ottime performance energetiche e di isolamento termico, il profilo InOpera. Sistema monoblocco con profilo InOpera InOpera permette di [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[57],"tags":[],"class_list":["post-2580","post","type-post","status-publish","format-standard","hentry","category-normativa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ogni OPERA ha la cornice che si merita, come ogni finestra! - CFD FEA\/FEM Service<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ogni OPERA ha la cornice che si merita, come ogni finestra! - CFD FEA\/FEM Service\" \/>\n<meta property=\"og:description\" content=\"In un\u2019ottica di continua attenzione ai dettagli e alla qualit\u00e0 dei prodotti forniti, De Faveri ha incluso nella sua proposta, per delle case che sappiano distinguersi sia per design che per le ottime performance energetiche e di isolamento termico, il profilo InOpera. Sistema monoblocco con profilo InOpera InOpera permette di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/\" \/>\n<meta property=\"og:site_name\" content=\"CFD FEA\/FEM Service\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cfdfeaservice\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-12T02:03:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unionegeometri.com\/wp-content\/uploads\/2019\/03\/INQUADRA-860X430-1.jpg\" \/>\n<meta name=\"author\" content=\"CFD FEA SERVICE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"CFD FEA SERVICE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/\"},\"author\":{\"name\":\"CFD FEA SERVICE\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\"},\"headline\":\"Ogni OPERA ha la cornice che si merita, come ogni finestra!\",\"datePublished\":\"2019-03-12T02:03:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/\"},\"wordCount\":338,\"publisher\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.unionegeometri.com\/wp-content\/uploads\/2019\/03\/INQUADRA-860X430-1.jpg\",\"articleSection\":[\"Normativa\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/\",\"url\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/\",\"name\":\"Ogni OPERA ha la cornice che si merita, come ogni finestra! - CFD FEA\/FEM Service\",\"isPartOf\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.unionegeometri.com\/wp-content\/uploads\/2019\/03\/INQUADRA-860X430-1.jpg\",\"datePublished\":\"2019-03-12T02:03:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/#primaryimage\",\"url\":\"https:\/\/www.unionegeometri.com\/wp-content\/uploads\/2019\/03\/INQUADRA-860X430-1.jpg\",\"contentUrl\":\"https:\/\/www.unionegeometri.com\/wp-content\/uploads\/2019\/03\/INQUADRA-860X430-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cfdfeaservice.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ogni OPERA ha la cornice che si merita, come ogni finestra!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cfdfeaservice.it\/#website\",\"url\":\"https:\/\/cfdfeaservice.it\/\",\"name\":\"CFD FEA\/FEM Service\",\"description\":\"Servizi di ingegneria 4.0\",\"publisher\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cfdfeaservice.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\",\"name\":\"CFD FEA SERVICE SRL\",\"url\":\"https:\/\/cfdfeaservice.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"contentUrl\":\"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"width\":677,\"height\":178,\"caption\":\"CFD FEA SERVICE SRL\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cfdfeaservice\",\"https:\/\/www.linkedin.com\/company\/11421185\/\",\"https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\",\"name\":\"CFD FEA SERVICE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"caption\":\"CFD FEA SERVICE\"},\"url\":\"https:\/\/cfdfeaservice.it\/index.php\/author\/cfd-fea-service\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ogni OPERA ha la cornice che si merita, come ogni finestra! - CFD FEA\/FEM Service","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/","og_locale":"en_GB","og_type":"article","og_title":"Ogni OPERA ha la cornice che si merita, come ogni finestra! - CFD FEA\/FEM Service","og_description":"In un\u2019ottica di continua attenzione ai dettagli e alla qualit\u00e0 dei prodotti forniti, De Faveri ha incluso nella sua proposta, per delle case che sappiano distinguersi sia per design che per le ottime performance energetiche e di isolamento termico, il profilo InOpera. Sistema monoblocco con profilo InOpera InOpera permette di [&hellip;]","og_url":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/","og_site_name":"CFD FEA\/FEM Service","article_publisher":"https:\/\/www.facebook.com\/cfdfeaservice","article_published_time":"2019-03-12T02:03:54+00:00","og_image":[{"url":"https:\/\/www.unionegeometri.com\/wp-content\/uploads\/2019\/03\/INQUADRA-860X430-1.jpg","type":"","width":"","height":""}],"author":"CFD FEA SERVICE","twitter_card":"summary_large_image","twitter_misc":{"Written by":"CFD FEA SERVICE","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/#article","isPartOf":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/"},"author":{"name":"CFD FEA SERVICE","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7"},"headline":"Ogni OPERA ha la cornice che si merita, come ogni finestra!","datePublished":"2019-03-12T02:03:54+00:00","mainEntityOfPage":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/"},"wordCount":338,"publisher":{"@id":"https:\/\/cfdfeaservice.it\/#organization"},"image":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unionegeometri.com\/wp-content\/uploads\/2019\/03\/INQUADRA-860X430-1.jpg","articleSection":["Normativa"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/","url":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/","name":"Ogni OPERA ha la cornice che si merita, come ogni finestra! - CFD FEA\/FEM Service","isPartOf":{"@id":"https:\/\/cfdfeaservice.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/#primaryimage"},"image":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unionegeometri.com\/wp-content\/uploads\/2019\/03\/INQUADRA-860X430-1.jpg","datePublished":"2019-03-12T02:03:54+00:00","breadcrumb":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/#primaryimage","url":"https:\/\/www.unionegeometri.com\/wp-content\/uploads\/2019\/03\/INQUADRA-860X430-1.jpg","contentUrl":"https:\/\/www.unionegeometri.com\/wp-content\/uploads\/2019\/03\/INQUADRA-860X430-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/12\/ogni-opera-ha-la-cornice-che-si-merita-come-ogni-finestra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cfdfeaservice.it\/"},{"@type":"ListItem","position":2,"name":"Ogni OPERA ha la cornice che si merita, come ogni finestra!"}]},{"@type":"WebSite","@id":"https:\/\/cfdfeaservice.it\/#website","url":"https:\/\/cfdfeaservice.it\/","name":"CFD FEA\/FEM Service","description":"Servizi di ingegneria 4.0","publisher":{"@id":"https:\/\/cfdfeaservice.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cfdfeaservice.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cfdfeaservice.it\/#organization","name":"CFD FEA SERVICE SRL","url":"https:\/\/cfdfeaservice.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1","contentUrl":"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1","width":677,"height":178,"caption":"CFD FEA SERVICE SRL"},"image":{"@id":"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cfdfeaservice","https:\/\/www.linkedin.com\/company\/11421185\/","https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA"]},{"@type":"Person","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7","name":"CFD FEA SERVICE","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g","caption":"CFD FEA SERVICE"},"url":"https:\/\/cfdfeaservice.it\/index.php\/author\/cfd-fea-service\/"}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p9JrPq-FC","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/2580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/comments?post=2580"}],"version-history":[{"count":0,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/2580\/revisions"}],"wp:attachment":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/media?parent=2580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/categories?post=2580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/tags?post=2580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}