{"id":2598,"date":"2019-03-15T03:01:46","date_gmt":"2019-03-15T02:01:46","guid":{"rendered":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/"},"modified":"2019-03-15T03:01:46","modified_gmt":"2019-03-15T02:01:46","slug":"mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0","status":"publish","type":"post","link":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/","title":{"rendered":"MecSpe 2019: la fiera dell\u2019innovazione e dell\u2019industria 4.0"},"content":{"rendered":"<div>\n<div style=\"margin: 5px 5% 10px 5%;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.ilprogettistaindustriale.it\/files\/2019\/03\/DSC_9192-1024x678.jpg?resize=750%2C497&#038;ssl=1\" width=\"750\" height=\"497\" title=\"\" alt=\"\"><\/div>\n<div>\n<p>Presentata l\u2019edizione 2019 di <strong><a href=\"http:\/\/www.mecspe.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mecspe<\/a>,<\/strong> la fiera delle tecnologie per l\u2019innovazione e l\u2019Industria 4.0 che con 2.330 aziende presenti in 12 saloni (suddivisi in 8 padiglioni), 32 convegni in programma e 55.000 visitatori attesi si prospetta l\u2019evento pi\u00f9 importante per il settore manifatturiero in Italia. Novit\u00e0 di rilievo di quest\u2019anno il <a href=\"https:\/\/www.meccanicanews.com\/2019\/02\/28\/mecspe-lighthouse-plant\/\" target=\"_blank\" rel=\"noopener noreferrer\">Tunnel dell\u2019Innovazione<\/a> e <a href=\"https:\/\/www.mecspe.com\/it\/initiative\/mecspe-young-career\" target=\"_blank\" rel=\"noopener noreferrer\">MECSPE Young&#038;Carrier.<\/a><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.ilprogettistaindustriale.it\/files\/2019\/03\/mecspe_aecas2019.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-19186 aligncenter\" src=\"https:\/\/i0.wp.com\/www.ilprogettistaindustriale.it\/files\/2019\/03\/mecspe_aecas2019-300x127.jpg?resize=300%2C127&#038;ssl=1\" alt=\"\" width=\"300\" height=\"127\" srcset=\"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/mecspe_aecas2019-300x127.jpg 300w, https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/mecspe_aecas2019.jpg 591w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><\/a><\/p>\n<p><strong>Il discorso di Ivo Nardella, Amministratore Delegato del <a href=\"http:\/\/www.gruppotecnichenuove.it\/\" target=\"_blank\" rel=\"noopener noreferrer\">Gruppo Tecniche Nuove<\/a><\/strong><\/p>\n<p>Buongiorno a tutti, nonostante tutto \u00e8 una bella giornata e sull\u2019Italia splende sempre il sole, un sole forte che attiva processi positivi, innovativi e alle volte rivoluzionari quel tanto che basta. Siamo per\u00f2 timidi nell\u2019apprezzare quello che abbiamo e alle volte ancor pi\u00f9 timidi a gridarlo al mondo.Eppure, spesso, pi\u00f9 del 50% delle auto tedesche \u00e8 costituito da <strong>componentistica<\/strong> italiana, i pi\u00f9 grandi produttori di bevande, birra, vino e liquori utilizzano impianti sviluppati, costruiti e pensati in Italia. Sarebbe troppo facile parlare poi di fashion, food &#038; furniture senza scendere nel dettaglio dei processi produttivi che coinvolgono migliaia di PMI della penisola.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.ilprogettistaindustriale.it\/files\/2019\/03\/IMG_3149.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-19181 alignright\" src=\"https:\/\/i0.wp.com\/www.ilprogettistaindustriale.it\/files\/2019\/03\/IMG_3149-300x225.jpg?resize=300%2C225&#038;ssl=1\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/IMG_3149-300x225.jpg 300w, https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/IMG_3149-768x576.jpg 768w, https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/IMG_3149-1024x768.jpg 1024w, https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/IMG_3149-80x60.jpg 80w, https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/IMG_3149-265x198.jpg 265w, https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/IMG_3149-696x522.jpg 696w, https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/IMG_3149-1068x801.jpg 1068w, https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/IMG_3149-560x420.jpg 560w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><\/a>I primi tessuti in <strong>grafene<\/strong> erano gi\u00e0 presenti a Mecspe quattro anni fa prima ancora di sfilare sulle passerelle milanesi.<\/p>\n<p><strong>Materiali intelligenti<\/strong> che ricoprono i battistrada delle biciclette dei nostri campioni li portano alla vittoria grazie alla ricerca dei poli d\u2019eccellenza dei nostri politecnici.<\/p>\n<p><strong>Internet of Things<\/strong> applicata alla medicina, monitorizza, avverte, coadiuva il processo curativo e preventivo grazie a sensori, tecnologie e software frutto del genius loci, espressione che mi permetto di rubare al contesto architettonico.<\/p>\n<p>Migliaia sono gli esempi del fare e del proporre che troverete in <a href=\"http:\/\/www.mecspe.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mecspe 2019<\/a>.<\/p>\n<p>Mecspe \u00e8 il punto di arrivo di un processo comunicativo che il nostro <a href=\"http:\/\/www.gruppotecnichenuove.it\/\">gruppo<\/a> compie quotidianamente tramite le svariate piattaforme editoriali, una produzione costante da 54 anni di manuali tecnici che affiancano l\u2019industria, corsi di formazione focus group e tutto ci\u00f2 che serve a mantenere alto il livello di professionalit\u00e0 di piccole, medie e grandi aziende.<\/p>\n<p>Mecspe \u00e8 anche il punto di partenza e <strong>lo stimolo a trovare idee nuove e innovative<\/strong>. Un contaminatore sano di trasferimenti tecnologici e spunti di riflessione progettuali. Tutto questo viene condensato nel nostro \u201ccuore mostra\u201d che quest\u2019anno prende il nome di \u201cTunnel dell\u2019innovazione\u201d per il quale ringrazio oltre a tutto lo staff di Mecspe capitanato da Maruska sabato con l\u2019aiuto del nostro direttore Emilio Bianchi anche e soprattutto il \u201cCluster Fabbrica Intelligente\u201d che con gli oltre 300 soci tra imprese, universit\u00e0, centri di ricerca vedr\u00e0 protagonisti quattro LightHouse Plant, quattro progetti che il cluster ha selezionato insieme a noi per conto del MISE come esempi concreti del piano Industria 4.0 da mostrare all\u2019Italia e all\u2019estero.<\/p>\n<p><strong>Il Tunnel dell\u2019innovazione a MECSPE 2019<\/strong><\/p>\n<p>MECSPE \u00e8 luogo di innovazione e riferimento della <strong>manifattura 4.0<\/strong> italiana e internazionale. Nella prossima edizione offrir\u00e0 la panoramica pi\u00f9 completa e aggiornata sui pi\u00f9 importanti trend del mercato, in particolare all\u2019interno del \u201cTunnel dell\u2019innovazione\u201d, nuovo cuore mostra della fiera (padiglione 4, Ingresso Sud). In questo spazio verranno presentati i quattro lighthouse plant, progetti appartenenti ad <a href=\"https:\/\/www.mecspe.com\/it\/appuntamenti\/intervista_ansaldo_energia\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ansaldo Energia<\/a>, <a href=\"https:\/\/www.mecspe.com\/it\/appuntamenti\/intervista_abb_italia\/\" target=\"_blank\" rel=\"noopener noreferrer\">ABB Italia<\/a>, <a href=\"https:\/\/www.mecspe.com\/it\/appuntamenti\/intervista-a-tenova-orimartin\/\" target=\"_blank\" rel=\"noopener noreferrer\">Tenova\/ORI Martin<\/a> e <a href=\"https:\/\/www.mecspe.com\/it\/appuntamenti\/intervista_hitachi_rail\/\" target=\"_blank\" rel=\"noopener noreferrer\">Hitachi Rail Italy<\/a>, soci del <a href=\"https:\/\/www.fabbricaintelligente.it\/\" target=\"_blank\" rel=\"noopener noreferrer\">Cluster Fabbrica Intelligente<\/a>, fiori all\u2019occhiello del Made in Italy e del saper fare nazionale. Dei veri e propri impianti produttivi da esplorare basati sullo sviluppo e applicazione delle tecnologie digitali previste nel piano Industria 4.0, che oltre agli aspetti organizzativi e tecnologici mettono in evidenza altri principi: la centralit\u00e0 dell\u2019uomo nel suo ruolo, nel rispetto di dignit\u00e0 e sicurezza; la necessit\u00e0 della collaborazione come unica via percorribile per rafforzare la competitivit\u00e0 e il valore aziendale.<\/p>\n<div class=\"su-button-center\"><a href=\"https:\/\/www.mecspe.com\/it\/ingressi-gratuiti-biglietti\/\" class=\"su-button su-button-style-default su-button-wide\" style=\"color:#FFFFFF;background-color:#efa42d;border-color:#bf8324;border-radius:6px;-moz-border-radius:6px;-webkit-border-radius:6px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 18px;font-size:14px;line-height:28px;border-color:#f4bf6c;border-radius:6px;-moz-border-radius:6px;-webkit-border-radius:6px;text-shadow:none;-moz-text-shadow:none;-webkit-text-shadow:none\"> Richiedi il tuo biglietto di ingresso gratuito a MecSpe<\/span><\/a><\/div>\n<div class=\"su-button-center\"><a href=\"https:\/\/secure.viewer.zmags.com\/publication\/7be3fbe9#\/7be3fbe9\/1\" class=\"su-button su-button-style-default su-button-wide\" style=\"color:#FFFFFF;background-color:#efa42d;border-color:#bf8324;border-radius:6px;-moz-border-radius:6px;-webkit-border-radius:6px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 18px;font-size:14px;line-height:28px;border-color:#f4bf6c;border-radius:6px;-moz-border-radius:6px;-webkit-border-radius:6px;text-shadow:none;-moz-text-shadow:none;-webkit-text-shadow:none\"> Sfoglia o scarica gratuitamente il giornale con tutte le anteprime di MecSpe<\/span><\/a><\/div>\n<div class=\"su-button-center\"><\/div>\n<\/div>\n<p>L&#8217;articolo <a rel=\"nofollow\" href=\"https:\/\/www.ilprogettistaindustriale.it\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/\">MecSpe 2019: la fiera dell\u2019innovazione e dell\u2019industria 4.0<\/a> sembra essere il primo su <a rel=\"nofollow\" href=\"https:\/\/www.ilprogettistaindustriale.it\/\">Il Progettista Industriale<\/a>.<\/p>\n<\/div>\n<p><a href=\"https:\/\/www.ilprogettistaindustriale.it\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/\">Vai alla fonte.<\/a><\/p>\n<p>Autore: Redazione<\/p>\n<p class=\"wpematico_credit\"><small>Powered by <a href=\"http:\/\/www.wpematico.com\" target=\"_blank\" rel=\"noopener noreferrer\">WPeMatico<\/a><\/small><\/p>\n<p><strong>_________________________________<\/strong><\/p>\n<p><strong>CFD FEA Service SRL<\/strong> &egrave; una societ&agrave; di servizi che offre <em>consulenza<\/em> e <em>formazione<\/em> in ambito <strong>ingegneria<\/strong> e <strong>IT<\/strong>. Se questo post\/prodotto ti &egrave; piaciuto ti invitiamo a:<\/p>\n<ul>\n<li>visionare il nostro <a href=\"https:\/\/cfdfeaservice.it\/index.php\/blog\/\" target=\"_blank\" rel=\"noopener\">blog<\/a><\/li>\n<li>visionare i <a href=\"https:\/\/cfdfeaservice.it\/index.php\/prodotti\/\" target=\"_blank\" rel=\"noopener\">software<\/a> disponibili - anche per la formazione<\/li>\n<li>iscriverti alla nostra newsletter<\/li>\n<li>entrare in contatto con noi attraverso la <a href=\"https:\/\/cfdfeaservice.it\/#ribbon\" target=\"_blank\" rel=\"noopener\">pagina contatti<\/a><\/li>\n<\/ul>\n<p>Saremo lieti di seguire le tue richieste e fornire risposte alle tue domande.<\/p>","protected":false},"excerpt":{"rendered":"<p>Presentata l\u2019edizione 2019 di Mecspe, la fiera delle tecnologie per l\u2019innovazione e l\u2019Industria 4.0 che con 2.330 aziende presenti in 12 saloni (suddivisi in 8 padiglioni), 32 convegni in programma e 55.000 visitatori attesi si prospetta l\u2019evento pi\u00f9 importante per il settore manifatturiero in Italia. Novit\u00e0 di rilievo di quest\u2019anno [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[57],"tags":[],"class_list":["post-2598","post","type-post","status-publish","format-standard","hentry","category-normativa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MecSpe 2019: la fiera dell\u2019innovazione e dell\u2019industria 4.0 - CFD FEA\/FEM Service<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MecSpe 2019: la fiera dell\u2019innovazione e dell\u2019industria 4.0 - CFD FEA\/FEM Service\" \/>\n<meta property=\"og:description\" content=\"Presentata l\u2019edizione 2019 di Mecspe, la fiera delle tecnologie per l\u2019innovazione e l\u2019Industria 4.0 che con 2.330 aziende presenti in 12 saloni (suddivisi in 8 padiglioni), 32 convegni in programma e 55.000 visitatori attesi si prospetta l\u2019evento pi\u00f9 importante per il settore manifatturiero in Italia. Novit\u00e0 di rilievo di quest\u2019anno [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/\" \/>\n<meta property=\"og:site_name\" content=\"CFD FEA\/FEM Service\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cfdfeaservice\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-15T02:01:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/DSC_9192-1024x678.jpg\" \/>\n<meta name=\"author\" content=\"CFD FEA SERVICE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"CFD FEA SERVICE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/\"},\"author\":{\"name\":\"CFD FEA SERVICE\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\"},\"headline\":\"MecSpe 2019: la fiera dell\u2019innovazione e dell\u2019industria 4.0\",\"datePublished\":\"2019-03-15T02:01:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/\"},\"wordCount\":636,\"publisher\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/DSC_9192-1024x678.jpg\",\"articleSection\":[\"Normativa\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/\",\"url\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/\",\"name\":\"MecSpe 2019: la fiera dell\u2019innovazione e dell\u2019industria 4.0 - CFD FEA\/FEM Service\",\"isPartOf\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/DSC_9192-1024x678.jpg\",\"datePublished\":\"2019-03-15T02:01:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/#primaryimage\",\"url\":\"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/DSC_9192-1024x678.jpg\",\"contentUrl\":\"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/DSC_9192-1024x678.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cfdfeaservice.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MecSpe 2019: la fiera dell\u2019innovazione e dell\u2019industria 4.0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cfdfeaservice.it\/#website\",\"url\":\"https:\/\/cfdfeaservice.it\/\",\"name\":\"CFD FEA\/FEM Service\",\"description\":\"Servizi di ingegneria 4.0\",\"publisher\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cfdfeaservice.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\",\"name\":\"CFD FEA SERVICE SRL\",\"url\":\"https:\/\/cfdfeaservice.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"contentUrl\":\"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"width\":677,\"height\":178,\"caption\":\"CFD FEA SERVICE SRL\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cfdfeaservice\",\"https:\/\/www.linkedin.com\/company\/11421185\/\",\"https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\",\"name\":\"CFD FEA SERVICE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"caption\":\"CFD FEA SERVICE\"},\"url\":\"https:\/\/cfdfeaservice.it\/index.php\/author\/cfd-fea-service\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MecSpe 2019: la fiera dell\u2019innovazione e dell\u2019industria 4.0 - CFD FEA\/FEM Service","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/","og_locale":"en_GB","og_type":"article","og_title":"MecSpe 2019: la fiera dell\u2019innovazione e dell\u2019industria 4.0 - CFD FEA\/FEM Service","og_description":"Presentata l\u2019edizione 2019 di Mecspe, la fiera delle tecnologie per l\u2019innovazione e l\u2019Industria 4.0 che con 2.330 aziende presenti in 12 saloni (suddivisi in 8 padiglioni), 32 convegni in programma e 55.000 visitatori attesi si prospetta l\u2019evento pi\u00f9 importante per il settore manifatturiero in Italia. Novit\u00e0 di rilievo di quest\u2019anno [&hellip;]","og_url":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/","og_site_name":"CFD FEA\/FEM Service","article_publisher":"https:\/\/www.facebook.com\/cfdfeaservice","article_published_time":"2019-03-15T02:01:46+00:00","og_image":[{"url":"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/DSC_9192-1024x678.jpg","type":"","width":"","height":""}],"author":"CFD FEA SERVICE","twitter_card":"summary_large_image","twitter_misc":{"Written by":"CFD FEA SERVICE","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/#article","isPartOf":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/"},"author":{"name":"CFD FEA SERVICE","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7"},"headline":"MecSpe 2019: la fiera dell\u2019innovazione e dell\u2019industria 4.0","datePublished":"2019-03-15T02:01:46+00:00","mainEntityOfPage":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/"},"wordCount":636,"publisher":{"@id":"https:\/\/cfdfeaservice.it\/#organization"},"image":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/DSC_9192-1024x678.jpg","articleSection":["Normativa"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/","url":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/","name":"MecSpe 2019: la fiera dell\u2019innovazione e dell\u2019industria 4.0 - CFD FEA\/FEM Service","isPartOf":{"@id":"https:\/\/cfdfeaservice.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/#primaryimage"},"image":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/DSC_9192-1024x678.jpg","datePublished":"2019-03-15T02:01:46+00:00","breadcrumb":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/#primaryimage","url":"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/DSC_9192-1024x678.jpg","contentUrl":"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/DSC_9192-1024x678.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/15\/mecspe-2019-la-fiera-dellinnovazione-e-dellindustria-4-0\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cfdfeaservice.it\/"},{"@type":"ListItem","position":2,"name":"MecSpe 2019: la fiera dell\u2019innovazione e dell\u2019industria 4.0"}]},{"@type":"WebSite","@id":"https:\/\/cfdfeaservice.it\/#website","url":"https:\/\/cfdfeaservice.it\/","name":"CFD FEA\/FEM Service","description":"Servizi di ingegneria 4.0","publisher":{"@id":"https:\/\/cfdfeaservice.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cfdfeaservice.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cfdfeaservice.it\/#organization","name":"CFD FEA SERVICE SRL","url":"https:\/\/cfdfeaservice.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1","contentUrl":"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1","width":677,"height":178,"caption":"CFD FEA SERVICE SRL"},"image":{"@id":"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cfdfeaservice","https:\/\/www.linkedin.com\/company\/11421185\/","https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA"]},{"@type":"Person","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7","name":"CFD FEA SERVICE","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g","caption":"CFD FEA SERVICE"},"url":"https:\/\/cfdfeaservice.it\/index.php\/author\/cfd-fea-service\/"}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p9JrPq-FU","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/2598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/comments?post=2598"}],"version-history":[{"count":0,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/2598\/revisions"}],"wp:attachment":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/media?parent=2598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/categories?post=2598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/tags?post=2598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}