{"id":2636,"date":"2019-03-22T03:01:04","date_gmt":"2019-03-22T02:01:04","guid":{"rendered":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/"},"modified":"2019-03-22T03:01:04","modified_gmt":"2019-03-22T02:01:04","slug":"tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar","status":"publish","type":"post","link":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/","title":{"rendered":"Tool di simulazione integrati nel CAD \u2013 Guarda l\u2019ultimo webinar"},"content":{"rendered":"<div>\n<div style=\"margin: 5px 5% 10px 5%;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.ilprogettistaindustriale.it\/files\/2019\/03\/Schermata-2019-03-21-alle-10.37.58.png?resize=750%2C424&#038;ssl=1\" width=\"750\" height=\"424\" title=\"\" alt=\"\"><\/div>\n<div>\n<p>Guarda l\u2019ultimo webinar organizzato da \u201cIl Progettista Industriale\u201d sul tema della simulazione numerica. L\u2019Ing. Matteo Vettori, esperto di simulazione racconta l\u2019evoluzione dei tool di simulazione integrati negli <a href=\"https:\/\/www.ilprogettistaindustriale.it\/cad-3d\/\" target=\"_blank\" rel=\"noopener noreferrer\">applicativi CAD<\/a>, ne analizza i principali vantaggi e cerca di sfatare i \u201cfalsi miti\u201d: i\u00a0risultati delle simulazioni saranno affidabili? Sar\u00e0 semplice impostare le analisi? \u00c8 necessario avere conoscenze ingegneristiche e di quale livello? Il processo di simulazione rallenta la creazione del progetto? Fino a quale grado di complessit\u00e0 ci possiamo spingere nelle simulazioni rispetto ai software dedicati?<\/p>\n<p>Nel webinar, sponsorizzato da <a href=\"http:\/\/www.ptc.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">PTC<\/a>, intervengono Fabrizio Ferro e Gabriele Giuliani che illustrano i principi di funzionamento e i vantaggi della soluzione <strong><a href=\"https:\/\/www.ptc.com\/it\/products\/cad\/creo\/simulation-live-trial?utm_source=Progettista_Industriale&#038;utm_medium=referral&#038;utm_campaign=Creo_Simulation_Progettista_Industriale_CLC&#038;utm_content=Creo_Simulation_Progettista_Industriale_CLC-referral-Creo_Made_In_Italy_Progettista_Microsite_CLC-33401&#038;cl1=Creo_Simulation_Progettista_Industriale_CLC-referral-Creo_Made_In_Italy_Progettista_Microsite_CLC-33401&#038;cmsrc=Progettista_Industriale&#038;cid=7015A000001oU3NQAU&#038;elqCampaignId=13771\" target=\"_blank\" rel=\"noopener noreferrer\">Creo Simulation Live<\/a><\/strong>.<\/p>\n<div class=\"su-button-center\"><a href=\"https:\/\/www.surveygizmo.com\/s3\/4908896\/TN-Webinar-PTC-15-03-2019\" class=\"su-button su-button-style-default su-button-wide\" style=\"color:#FFFFFF;background-color:#efa42d;border-color:#bf8324;border-radius:6px;-moz-border-radius:6px;-webkit-border-radius:6px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 18px;font-size:14px;line-height:28px;border-color:#f4bf6c;border-radius:6px;-moz-border-radius:6px;-webkit-border-radius:6px;text-shadow:none;-moz-text-shadow:none;-webkit-text-shadow:none\"> Guarda il Webinar<\/span><\/a><\/div>\n<\/div>\n<p>L&#8217;articolo <a rel=\"nofollow\" href=\"https:\/\/www.ilprogettistaindustriale.it\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/\">Tool di simulazione integrati nel CAD \u2013 Guarda l\u2019ultimo webinar<\/a> sembra essere il primo su <a rel=\"nofollow\" href=\"https:\/\/www.ilprogettistaindustriale.it\/\">Il Progettista Industriale<\/a>.<\/p>\n<\/div>\n<p><a href=\"https:\/\/www.ilprogettistaindustriale.it\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/\">Vai alla fonte.<\/a><\/p>\n<p>Autore: Alessandro Garnero<\/p>\n<p class=\"wpematico_credit\"><small>Powered by <a href=\"http:\/\/www.wpematico.com\" target=\"_blank\" rel=\"noopener noreferrer\">WPeMatico<\/a><\/small><\/p>\n<p><strong>_________________________________<\/strong><\/p>\n<p><strong>CFD FEA Service SRL<\/strong> &egrave; una societ&agrave; di servizi che offre <em>consulenza<\/em> e <em>formazione<\/em> in ambito <strong>ingegneria<\/strong> e <strong>IT<\/strong>. Se questo post\/prodotto ti &egrave; piaciuto ti invitiamo a:<\/p>\n<ul>\n<li>visionare il nostro <a href=\"https:\/\/cfdfeaservice.it\/index.php\/blog\/\" target=\"_blank\" rel=\"noopener\">blog<\/a><\/li>\n<li>visionare i <a href=\"https:\/\/cfdfeaservice.it\/index.php\/prodotti\/\" target=\"_blank\" rel=\"noopener\">software<\/a> disponibili - anche per la formazione<\/li>\n<li>iscriverti alla nostra newsletter<\/li>\n<li>entrare in contatto con noi attraverso la <a href=\"https:\/\/cfdfeaservice.it\/#ribbon\" target=\"_blank\" rel=\"noopener\">pagina contatti<\/a><\/li>\n<\/ul>\n<p>Saremo lieti di seguire le tue richieste e fornire risposte alle tue domande.<\/p>","protected":false},"excerpt":{"rendered":"<p>Guarda l\u2019ultimo webinar organizzato da \u201cIl Progettista Industriale\u201d sul tema della simulazione numerica. L\u2019Ing. Matteo Vettori, esperto di simulazione racconta l\u2019evoluzione dei tool di simulazione integrati negli applicativi CAD, ne analizza i principali vantaggi e cerca di sfatare i \u201cfalsi miti\u201d: i\u00a0risultati delle simulazioni saranno affidabili? Sar\u00e0 semplice impostare le [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[57],"tags":[],"class_list":["post-2636","post","type-post","status-publish","format-standard","hentry","category-normativa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tool di simulazione integrati nel CAD \u2013 Guarda l\u2019ultimo webinar - CFD FEA\/FEM Service<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tool di simulazione integrati nel CAD \u2013 Guarda l\u2019ultimo webinar - CFD FEA\/FEM Service\" \/>\n<meta property=\"og:description\" content=\"Guarda l\u2019ultimo webinar organizzato da \u201cIl Progettista Industriale\u201d sul tema della simulazione numerica. L\u2019Ing. Matteo Vettori, esperto di simulazione racconta l\u2019evoluzione dei tool di simulazione integrati negli applicativi CAD, ne analizza i principali vantaggi e cerca di sfatare i \u201cfalsi miti\u201d: i\u00a0risultati delle simulazioni saranno affidabili? Sar\u00e0 semplice impostare le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/\" \/>\n<meta property=\"og:site_name\" content=\"CFD FEA\/FEM Service\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cfdfeaservice\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-22T02:01:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/Schermata-2019-03-21-alle-10.37.58.png\" \/>\n<meta name=\"author\" content=\"CFD FEA SERVICE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"CFD FEA SERVICE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/\"},\"author\":{\"name\":\"CFD FEA SERVICE\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\"},\"headline\":\"Tool di simulazione integrati nel CAD \u2013 Guarda l\u2019ultimo webinar\",\"datePublished\":\"2019-03-22T02:01:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/\"},\"wordCount\":154,\"publisher\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/Schermata-2019-03-21-alle-10.37.58.png\",\"articleSection\":[\"Normativa\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/\",\"url\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/\",\"name\":\"Tool di simulazione integrati nel CAD \u2013 Guarda l\u2019ultimo webinar - CFD FEA\/FEM Service\",\"isPartOf\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/Schermata-2019-03-21-alle-10.37.58.png\",\"datePublished\":\"2019-03-22T02:01:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/#primaryimage\",\"url\":\"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/Schermata-2019-03-21-alle-10.37.58.png\",\"contentUrl\":\"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/Schermata-2019-03-21-alle-10.37.58.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cfdfeaservice.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tool di simulazione integrati nel CAD \u2013 Guarda l\u2019ultimo webinar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cfdfeaservice.it\/#website\",\"url\":\"https:\/\/cfdfeaservice.it\/\",\"name\":\"CFD FEA\/FEM Service\",\"description\":\"Servizi di ingegneria 4.0\",\"publisher\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cfdfeaservice.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\",\"name\":\"CFD FEA SERVICE SRL\",\"url\":\"https:\/\/cfdfeaservice.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"contentUrl\":\"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"width\":677,\"height\":178,\"caption\":\"CFD FEA SERVICE SRL\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cfdfeaservice\",\"https:\/\/www.linkedin.com\/company\/11421185\/\",\"https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\",\"name\":\"CFD FEA SERVICE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"caption\":\"CFD FEA SERVICE\"},\"url\":\"https:\/\/cfdfeaservice.it\/index.php\/author\/cfd-fea-service\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tool di simulazione integrati nel CAD \u2013 Guarda l\u2019ultimo webinar - CFD FEA\/FEM Service","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/","og_locale":"en_GB","og_type":"article","og_title":"Tool di simulazione integrati nel CAD \u2013 Guarda l\u2019ultimo webinar - CFD FEA\/FEM Service","og_description":"Guarda l\u2019ultimo webinar organizzato da \u201cIl Progettista Industriale\u201d sul tema della simulazione numerica. L\u2019Ing. Matteo Vettori, esperto di simulazione racconta l\u2019evoluzione dei tool di simulazione integrati negli applicativi CAD, ne analizza i principali vantaggi e cerca di sfatare i \u201cfalsi miti\u201d: i\u00a0risultati delle simulazioni saranno affidabili? Sar\u00e0 semplice impostare le [&hellip;]","og_url":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/","og_site_name":"CFD FEA\/FEM Service","article_publisher":"https:\/\/www.facebook.com\/cfdfeaservice","article_published_time":"2019-03-22T02:01:04+00:00","og_image":[{"url":"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/Schermata-2019-03-21-alle-10.37.58.png","type":"","width":"","height":""}],"author":"CFD FEA SERVICE","twitter_card":"summary_large_image","twitter_misc":{"Written by":"CFD FEA SERVICE","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/#article","isPartOf":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/"},"author":{"name":"CFD FEA SERVICE","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7"},"headline":"Tool di simulazione integrati nel CAD \u2013 Guarda l\u2019ultimo webinar","datePublished":"2019-03-22T02:01:04+00:00","mainEntityOfPage":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/"},"wordCount":154,"publisher":{"@id":"https:\/\/cfdfeaservice.it\/#organization"},"image":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/Schermata-2019-03-21-alle-10.37.58.png","articleSection":["Normativa"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/","url":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/","name":"Tool di simulazione integrati nel CAD \u2013 Guarda l\u2019ultimo webinar - CFD FEA\/FEM Service","isPartOf":{"@id":"https:\/\/cfdfeaservice.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/#primaryimage"},"image":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/Schermata-2019-03-21-alle-10.37.58.png","datePublished":"2019-03-22T02:01:04+00:00","breadcrumb":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/#primaryimage","url":"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/Schermata-2019-03-21-alle-10.37.58.png","contentUrl":"https:\/\/www.ilprogettistaindustriale.it\/files\/2019\/03\/Schermata-2019-03-21-alle-10.37.58.png"},{"@type":"BreadcrumbList","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/22\/tool-di-simulazione-integrati-nel-cad-guarda-lultimo-webinar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cfdfeaservice.it\/"},{"@type":"ListItem","position":2,"name":"Tool di simulazione integrati nel CAD \u2013 Guarda l\u2019ultimo webinar"}]},{"@type":"WebSite","@id":"https:\/\/cfdfeaservice.it\/#website","url":"https:\/\/cfdfeaservice.it\/","name":"CFD FEA\/FEM Service","description":"Servizi di ingegneria 4.0","publisher":{"@id":"https:\/\/cfdfeaservice.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cfdfeaservice.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cfdfeaservice.it\/#organization","name":"CFD FEA SERVICE SRL","url":"https:\/\/cfdfeaservice.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1","contentUrl":"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1","width":677,"height":178,"caption":"CFD FEA SERVICE SRL"},"image":{"@id":"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cfdfeaservice","https:\/\/www.linkedin.com\/company\/11421185\/","https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA"]},{"@type":"Person","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7","name":"CFD FEA SERVICE","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g","caption":"CFD FEA SERVICE"},"url":"https:\/\/cfdfeaservice.it\/index.php\/author\/cfd-fea-service\/"}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p9JrPq-Gw","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/2636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/comments?post=2636"}],"version-history":[{"count":0,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/2636\/revisions"}],"wp:attachment":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/media?parent=2636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/categories?post=2636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/tags?post=2636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}