{"id":2645,"date":"2019-03-23T03:01:24","date_gmt":"2019-03-23T02:01:24","guid":{"rendered":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/"},"modified":"2019-03-23T03:01:24","modified_gmt":"2019-03-23T02:01:24","slug":"valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi","status":"publish","type":"post","link":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/","title":{"rendered":"VALUTAZIONE DEL RISCHIO DA MOVIMENTAZIONE MANUALE DEI CARICHI, TRAINO SPINTA, MOVIMENTI RIPETITIVI"},"content":{"rendered":"<div>\n<p><a href=\"https:\/\/www.vegaengineering.com\/servizi\/1-valutazione_del_rischio_da_movimentazione_manuale_dei_carichi_traino_spinta_movimenti_ripetitivi-26.html\"><img decoding=\"async\" width=\"170\" border=\"0\" src=\"https:\/\/www.vegaengineering.com\/assets\/get_img.php?data=\/uploads\/servizi\/26.jpg&#038;width_output=200&#038;height_output=150\"><\/a><\/p>\n<p><strong>MOVIMENTAZIONE MANUALE DEI CARICHI, SOLLEVAMENTO E TRASPORTO, TRAINO-SPINTA E MOVIMENTI RIPETITIVI: COSA SONO E COME VALUTARE IL RISCHIO<\/strong><\/p>\n<p>Per <strong>Movimentazione Manuale dei Carichi<\/strong> (<strong>MMC<\/strong>) si intendono tutte le attivit\u00e0 che consistono in sollevare, deporre, spingere, tirare, portare o spostare un <strong>carico<\/strong> (<strong>art. 167, comma 2, <a href=\"https:\/\/www.vegaengineering.com\/download\/D.Lgs._81-2008_e_s.m.i._Rev0.4.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">D. Lgs. 81\/08<\/a><\/strong>). In effetti il <strong>rischio per la salute<\/strong> deve essere valutato non solo relativamente alle <i>azioni di sollevamento<\/i> (<strong>movimentazione manuale dei carichi<\/strong>) ma anche di<strong> traino spinta<\/strong> ed infine relativamente ai &#8220;cosiddetti&#8221; movimenti ripetuti o ripetitivi. Ancora oggi i rischi connessi con tali attivit\u00e0 lavorative sono tra i pi\u00f9 diffusi e spesso determinano malattie professionali.<br \/>\nLe v<i>alutazioni delle attivit\u00e0 di movimentazione manuale dei carichi<\/i> (<strong>MMC)<\/strong>, oltre a determinare il livello di rischio per la <i>sicurezza e la salute<\/i> a cui sono soggetti i lavoratori, consentono anche un&#8217;analisi critica delle modalit\u00e0 operative attuate in azienda e l&#8217;attuazione e\/o la programmazione di misure migliorative, dal punto di vista ergonomico, organizzativo e tecnico con risvolti sull&#8217;efficienza del sistema produttivo.<\/p>\n<p><strong>VEGA ENGINEERING E LA VALUTAZIONE DEL RISCHIO DA MOVIMENTAZIONE MANUALE DEI CARICHI (MMC) PER SOLLEVAMENTO E TRASPORTO, AZIONI TRAINO SPINTA E MOVIMENTI RIPETUTI<\/strong><\/p>\n<p>I tecnici di <i>Vega Engineering<\/i> sono dotati delle competenze e della strumentazione necessaria per effettuare la <strong>valutazione del rischio derivante dalla movimentazione manuale dei carichi<\/strong>, ai sensi del <i>D. Lgs. 81\/08<\/i>. Le <i>valutazioni dei rischi<\/i> sono effettuate in accordo con le <strong>norme UNI ISO 11228<\/strong>, <strong>ISO TR 12295<\/strong> e con la <strong>norma BS 18004 del 2008<\/strong>.<\/p>\n<p>Per richiedere un preventivo per effettuare la <strong>valutazione del rischio da movimentazione manuale dei carichi<\/strong>, sollevamento e trasporto, traino spinta o da movimenti ripetitivi, o per richiedere maggiori informazioni, \u00e8 possibile contattare i <i>tecnici di Vega Engineering<\/i> telefonando al numero 041 3963013 o compilando l&#8217;apposito form  <a href=\"https:\/\/www.vegaengineering.com\/contatti.php?richiesta=VALUTAZIONE+DEL+RISCHIO+DA+MOVIMENTAZIONE+MANUALE+DEI+CARICHI%2C+TRAINO+SPINTA%2C+MOVIMENTI+RIPETITIVI\" target=\"_blank\" rel=\"noopener noreferrer\">cliccando qui<\/a>.<\/p>\n<p>Per approfondire ulteriormente l&#8217;argomento, si segnalano infine i <a href=\"https:\/\/www.vegaformazione.it\/corsi\/24\/movimentazione_manuale_carichi_mmc\" target=\"_blank\" rel=\"noopener noreferrer\">corsi sui rischi derivanti dalla movimentazione manuale dei carichi<\/a>  organizzati da <strong>Vega Formazione<\/strong>, <i>ente di formazione accreditato<\/i>.<\/p>\n<p><strong>APPROFONDIMENTO SULLE METODOLOGIE DI VALUTAZIONE DEL RISCHIO DA MOVIMENTAZIONE MANUALE DEI CARICHI (MMC)<\/strong><\/p>\n<p>Il riferimento normativo per valutare i <strong>fattori di rischio connessi all&#8217;attivit\u00e0 di movimentazione manuale dei carichi<\/strong> \u00e8 rappresentato dal <strong>Titolo VI<\/strong> e dall&#8217;<strong>allegato XXXIII <\/strong>del <strong>D.Lgs. 81\/08 e s.m.i.<\/strong>.<br \/>\nL&#8217;art. 168 stabilisce che il Datore di Lavoro, tenendo conto dell&#8217;Allegato XXXIII, deve valutare, se possibile anche in fase di progettazione, le condizioni di sicurezza e di salute connesse alle attivit\u00e0 lavorative di movimentazione manuale dei carichi.<\/p>\n<p>Per effettuare la v<i>alutazione dei rischi<\/i> il <strong>Datore di Lavoro<\/strong> pu\u00f2 assumere le norme tecniche, ove applicabili, le buone prassi e le linee guida quali criteri di riferimento per l&#8217;adempimento dei propri obblighi (si ricordano fra gli altri i noti <strong>metodi NIOSH, OCRA e Snook Ciriello<\/strong>). Tra le norme tecniche da assumere come riferimento, il <strong>Testo Unico sulla Sicurezza<\/strong> specificatamente richiama le <strong>norme UNI ISO 11228 1, 2 e 3<\/strong>, alle quali si aggiunge la <strong>ISO TR 12295<\/strong>. Per visionare le numerose linee guida pubblicate sull&#8217;argomento, si rimanda alla <a href=\"https:\/\/www.vegaengineering.com\/banca_dati_linee_guida.php\" target=\"_blank\" rel=\"noopener noreferrer\">banca dati linee guida sicurezza<\/a>  di <i>Vega Engineering<\/i>, liberamente consultabile dagli utenti registrati gratuitamente nel nostro sito.<\/p>\n<p><strong>RISCHI PER LA SALUTE DELL&#8217;UOMO CAUSATI DALLA MOVIMENTAZIONE MANUALE DEI CARICHI (MMC)<\/strong><br \/>\nLa<strong> movimentazione manuale di carichi<\/strong> pu\u00f2 essere la causa dello sviluppo di <i>patologie<\/i> dovute alla graduale usura cumulativa dell&#8217;<strong>apparato muscolo-scheletrico<\/strong>, in particolare del rachide lombare, riconducibile a operazioni continue di <i>sollevamento o movimentazione<\/i> (per esempio, dolori dorso-lombari).<br \/>\nSi affianca, inoltre, il rischio legato al carico stesso che pu\u00f2 cadere provocando fratture o contusioni, pu\u00f2 essere caldo o tagliente e provocare quindi ustioni o ferite, pu\u00f2 essere ingombrante o instabile e impedire la vista di scalini o oggetti che si trovano a terra facendo inciampare chi lo trasporta.<\/p>\n<p><strong>LA NORMA UNI ISO 11228 E LA VALUTAZIONE DEL RISCHIO DA SOLLEVAMENTO E TRASPORTO, TRAINO SPINTA E MOVIMENTI RIPETUTI<\/strong><br \/><i>UNI ISO 11228-1 &#8220;Ergonomia &#8211; Movimentazione manuale &#8211; Parte 1: Sollevamento e trasporto&#8221;<\/i><\/p>\n<p>Per quanto concerne la <strong>valutazione del rischio da movimentazione manuale dei carichi <\/strong>(<strong>MMC<\/strong>) causato dalle <i>attivit\u00e0 di sollevamento e trasporto<\/i>, la <strong>norma UNI ISO 11228-1<\/strong> suggerisce un approccio simile al noto <strong>metodo NIOSH<\/strong> (1993), confrontando, per ogni compito di sollevamento, il peso effettivamente sollevato con il cosiddetto Peso Limite Raccomandato, attraverso un&#8217;equazione che, a partire da un peso massimo sollevabile in condizioni ideali, considera l&#8217;eventuale esistenza di fattori lavorativi sfavorevoli introducendo nell&#8217;equazione fattori moltiplicativi che per ciascun fattore considerato possono assumere valori compresi tra 0 e 1.<br \/>\nI <strong>fattori di rischio<\/strong> considerati nella <strong>norma UNI ISO 11228-1<\/strong> e nel <strong>metodo NIOSH<\/strong> corrispondono ai principali elementi di rischio lavorativo citati nell&#8217;<strong>Allegato XXXIII del D.Lgs. 81\/08<\/strong>.<br \/>\nLa <strong>norma UNI ISO 11228-1<\/strong> propone vari pesi iniziali in relazione alla popolazione prevista di utilizzatori (maschi, femmine, lavoratori adulti, lavoratori particolari). Per l&#8217;applicazione del metodo generalmente si considerano come pesi di riferimento massimi 25 kg per gli uomini e 20 kg per le donne.<\/p>\n<p><i>UNI ISO 11228-2 &#8220;Ergonomia &#8211; Movimentazione manuale &#8211; Parte 2: Spinta e traino&#8221;<\/i><br \/>\nPer quanto riguarda la <strong>valutazione del rischio dovuto alle azioni di traino-spinta<\/strong>, la <strong>norma UNI ISO 11228-2<\/strong> offre indicazioni per la valutazione dei fattori di rischio ritenuti rilevanti per le a<i>zioni manuali di spinta e traino<\/i>, e prevede due metodi di valutazione: un metodo &#8220;generale&#8221; ed un metodo &#8220;specialistico&#8221;.<br \/>\nL&#8217;approccio cosiddetto &#8220;generale&#8221; \u00e8 riconducibile in sostanza al metodo &#8220;<strong>Snook Ciriello<\/strong>&#8221; e si basa sull&#8217;utilizzo di tavole-tabelle sperimentali da cui ricavare i valori limite raccomandati da confrontare con i valori misurati delle azioni di traino e\/o spinta. Tale metodo per la valutazione del rischio connesso con le azioni di traino spinta richiede di poter misurare la forza richiesta per effettuare tali attivit\u00e0.<br \/>\nIl Metodo &#8220;specialistico&#8221; \u00e8 un metodo complesso che consente di effettuare la valutazione sulla base dei dati demografici ed antropometrici della popolazione in esame. A causa della sua complessit\u00e0, di fatto risulta un metodo di scarsa utilit\u00e0 pratica.<\/p>\n<p><strong>MISURAZIONI PER LA VALUTAZIONE DEL RISCHIO DA TRAINO SPINTA: IL DINAMOMETRO<\/strong><br \/>\nPer la misurazione e la valutazione degli sforzi che producono esposizione al <strong>rischio da sovraccarico biomeccanico<\/strong> dell&#8217;a<i>pparato muscolo-scheletrico<\/i> (ed in particolare del rachide), quali le azioni di traino, spinta e trasporto in piano, nonch\u00e9 quelle di sollevamento e\/o abbassamento di carichi, viene utilizzato il dinamometro, strumento per la misurazione della forza.<\/p>\n<p><i>UNI ISO 11228-3 &#8220;Ergonomia &#8211; Movimentazione manuale &#8211; Parte 3: Movimentazione di bassi carichi ad alta frequenza&#8221;<\/i><br \/>\nLe <strong>norme UNI ISO 11228-3<\/strong> e <strong>ISO TR 12295<\/strong> trattano la <strong>valutazione del rischio di movimenti ripetuti<\/strong>. La metodologia normalmente applicata per la <strong>valutazione del rischio da movimenti ripetuti<\/strong> si compone di due fasi: la prima fase consiste nello screening iniziale basato sull&#8217;uso di una check-list proposta dalla <strong>norma ISO TR 12295<\/strong>, e qualora necessario si prosegue con la seconda fase, pi\u00f9 dettagliata, che rimanda ad affermati e complessi metodi di analisi riconosciuti a livello internazionale, con una espressa preferenza per il <strong>Metodo OCRA<\/strong> (<strong>OCcupational Ripetitive Actions<\/strong>). Tale analisi richiede una specifica osservazione delle azioni tecniche effettuate, effettuabile utilizzando riprese video.<\/p>\n<p><i>ISO 11226 &#8220;Valutazione delle posture di lavoro statiche&#8221;<\/i> <br \/>\nLa <strong>norma ISO 11226<\/strong> considera i fattori derivanti da posture incongrue dei segmenti corporei, anche in assenza di m<strong>ovimentazione manuale dei carichi<\/strong>, compresi testa, collo, tronco, arti inferiori e piedi.<br \/>\nPer l&#8217;esecuzione della valutazione viene proposto il <strong>metodo REBA<\/strong> (<strong>Rapid Entire Body Assessment<\/strong>) che permette di calcolare l&#8217;indice relativo al <strong>rischio da posture di lavoro statiche e\/o incongrue<\/strong>.<br \/>\nIl <strong>D.lgs. 81\/08<\/strong>, seppur non prevede uno specifico titolo per il rischio posturale, indica nelle &#8220;<i>Misure generali di tutela<\/i>&#8221; <strong>art. 15 comma 1 lett. d)<\/strong> il &#8220;<i>rispetto dei principi ergonomici nell&#8217;organizzazione del lavoro, nella concezione dei posti di lavoro, nella scelta delle attrezzature e nella definizione dei metodi di lavoro e produzione, in particolare alla fine di ridurre gli effetti sulla salute del lavoro monotono e di quello ripetitivo<\/i>&#8221;. Pertanto il mancato rispetto dei principi ergonomici costituisce un fattore di rischio per la salute dei lavoratori.<br \/>\nGeneralmente gli aspetti inerenti il <strong>rischio posturale<\/strong> sono considerati con la <strong>valutazione del rischio da movimentazione manuale dei carichi<\/strong>, limitatamente al sovraccarico biomeccanico degli arti superiori e del tratto lombare, tuttavia la UNI ISO 11228 e le relative analisi non forniscono informazioni esaustive qualora le attivit\u00e0 lavorative comportassero prevalentemente l&#8217;assunzione di posture incongrue (in genere statiche &#8211; anche in assenza di <i>rischi da sollevamento di carichi, traino spinta e\/o movimenti ripetitivi<\/i>).<br \/>\nLa <strong>norma ISO 11226<\/strong> specifica i limiti raccomandati per le <strong>posture di lavoro statiche<\/strong> senza o con minimo esercizio di forma esterna, tenendo conto degli angoli del corpo e della durata dell&#8217;esposizione.<br \/>\nFornisce una linea guida sulla valutazione di diversi compiti tramite la stima dei <strong>rischi di salute<\/strong> per la popolazione lavorativa.<\/p>\n<\/div>\n<p><a href=\"https:\/\/www.vegaengineering.com\/servizi\/1-valutazione_del_rischio_da_movimentazione_manuale_dei_carichi_traino_spinta_movimenti_ripetitivi-26.html\">Vai alla fonte.<\/a><\/p>\n<p>Autore: <\/p>\n<p class=\"wpematico_credit\"><small>Powered by <a href=\"http:\/\/www.wpematico.com\" target=\"_blank\" rel=\"noopener noreferrer\">WPeMatico<\/a><\/small><\/p>\n<p><strong>_________________________________<\/strong><\/p>\n<p><strong>CFD FEA Service SRL<\/strong> &egrave; una societ&agrave; di servizi che offre <em>consulenza<\/em> e <em>formazione<\/em> in ambito <strong>ingegneria<\/strong> e <strong>IT<\/strong>. Se questo post\/prodotto ti &egrave; piaciuto ti invitiamo a:<\/p>\n<ul>\n<li>visionare il nostro <a href=\"https:\/\/cfdfeaservice.it\/index.php\/blog\/\" target=\"_blank\" rel=\"noopener\">blog<\/a><\/li>\n<li>visionare i <a href=\"https:\/\/cfdfeaservice.it\/index.php\/prodotti\/\" target=\"_blank\" rel=\"noopener\">software<\/a> disponibili - anche per la formazione<\/li>\n<li>iscriverti alla nostra newsletter<\/li>\n<li>entrare in contatto con noi attraverso la <a href=\"https:\/\/cfdfeaservice.it\/#ribbon\" target=\"_blank\" rel=\"noopener\">pagina contatti<\/a><\/li>\n<\/ul>\n<p>Saremo lieti di seguire le tue richieste e fornire risposte alle tue domande.<\/p>","protected":false},"excerpt":{"rendered":"<p>MOVIMENTAZIONE MANUALE DEI CARICHI, SOLLEVAMENTO E TRASPORTO, TRAINO-SPINTA E MOVIMENTI RIPETITIVI: COSA SONO E COME VALUTARE IL RISCHIO Per Movimentazione Manuale dei Carichi (MMC) si intendono tutte le attivit\u00e0 che consistono in sollevare, deporre, spingere, tirare, portare o spostare un carico (art. 167, comma 2, D. Lgs. 81\/08). In effetti [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[57],"tags":[],"class_list":["post-2645","post","type-post","status-publish","format-standard","hentry","category-normativa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VALUTAZIONE DEL RISCHIO DA MOVIMENTAZIONE MANUALE DEI CARICHI, TRAINO SPINTA, MOVIMENTI RIPETITIVI - CFD FEA\/FEM Service<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VALUTAZIONE DEL RISCHIO DA MOVIMENTAZIONE MANUALE DEI CARICHI, TRAINO SPINTA, MOVIMENTI RIPETITIVI - CFD FEA\/FEM Service\" \/>\n<meta property=\"og:description\" content=\"MOVIMENTAZIONE MANUALE DEI CARICHI, SOLLEVAMENTO E TRASPORTO, TRAINO-SPINTA E MOVIMENTI RIPETITIVI: COSA SONO E COME VALUTARE IL RISCHIO Per Movimentazione Manuale dei Carichi (MMC) si intendono tutte le attivit\u00e0 che consistono in sollevare, deporre, spingere, tirare, portare o spostare un carico (art. 167, comma 2, D. Lgs. 81\/08). In effetti [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/\" \/>\n<meta property=\"og:site_name\" content=\"CFD FEA\/FEM Service\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cfdfeaservice\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-23T02:01:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vegaengineering.com\/assets\/get_img.php?data=\/uploads\/servizi\/26.jpg&width_output=200&height_output=150\" \/>\n<meta name=\"author\" content=\"CFD FEA SERVICE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"CFD FEA SERVICE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/\"},\"author\":{\"name\":\"CFD FEA SERVICE\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\"},\"headline\":\"VALUTAZIONE DEL RISCHIO DA MOVIMENTAZIONE MANUALE DEI CARICHI, TRAINO SPINTA, MOVIMENTI RIPETITIVI\",\"datePublished\":\"2019-03-23T02:01:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/\"},\"wordCount\":1417,\"publisher\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vegaengineering.com\/assets\/get_img.php?data=\/uploads\/servizi\/26.jpg&width_output=200&height_output=150\",\"articleSection\":[\"Normativa\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/\",\"url\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/\",\"name\":\"VALUTAZIONE DEL RISCHIO DA MOVIMENTAZIONE MANUALE DEI CARICHI, TRAINO SPINTA, MOVIMENTI RIPETITIVI - CFD FEA\/FEM Service\",\"isPartOf\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vegaengineering.com\/assets\/get_img.php?data=\/uploads\/servizi\/26.jpg&width_output=200&height_output=150\",\"datePublished\":\"2019-03-23T02:01:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/#primaryimage\",\"url\":\"https:\/\/www.vegaengineering.com\/assets\/get_img.php?data=\/uploads\/servizi\/26.jpg&width_output=200&height_output=150\",\"contentUrl\":\"https:\/\/www.vegaengineering.com\/assets\/get_img.php?data=\/uploads\/servizi\/26.jpg&width_output=200&height_output=150\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cfdfeaservice.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VALUTAZIONE DEL RISCHIO DA MOVIMENTAZIONE MANUALE DEI CARICHI, TRAINO SPINTA, MOVIMENTI RIPETITIVI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cfdfeaservice.it\/#website\",\"url\":\"https:\/\/cfdfeaservice.it\/\",\"name\":\"CFD FEA\/FEM Service\",\"description\":\"Servizi di ingegneria 4.0\",\"publisher\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cfdfeaservice.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\",\"name\":\"CFD FEA SERVICE SRL\",\"url\":\"https:\/\/cfdfeaservice.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"contentUrl\":\"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"width\":677,\"height\":178,\"caption\":\"CFD FEA SERVICE SRL\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cfdfeaservice\",\"https:\/\/www.linkedin.com\/company\/11421185\/\",\"https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\",\"name\":\"CFD FEA SERVICE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"caption\":\"CFD FEA SERVICE\"},\"url\":\"https:\/\/cfdfeaservice.it\/index.php\/author\/cfd-fea-service\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VALUTAZIONE DEL RISCHIO DA MOVIMENTAZIONE MANUALE DEI CARICHI, TRAINO SPINTA, MOVIMENTI RIPETITIVI - CFD FEA\/FEM Service","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/","og_locale":"en_GB","og_type":"article","og_title":"VALUTAZIONE DEL RISCHIO DA MOVIMENTAZIONE MANUALE DEI CARICHI, TRAINO SPINTA, MOVIMENTI RIPETITIVI - CFD FEA\/FEM Service","og_description":"MOVIMENTAZIONE MANUALE DEI CARICHI, SOLLEVAMENTO E TRASPORTO, TRAINO-SPINTA E MOVIMENTI RIPETITIVI: COSA SONO E COME VALUTARE IL RISCHIO Per Movimentazione Manuale dei Carichi (MMC) si intendono tutte le attivit\u00e0 che consistono in sollevare, deporre, spingere, tirare, portare o spostare un carico (art. 167, comma 2, D. Lgs. 81\/08). In effetti [&hellip;]","og_url":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/","og_site_name":"CFD FEA\/FEM Service","article_publisher":"https:\/\/www.facebook.com\/cfdfeaservice","article_published_time":"2019-03-23T02:01:24+00:00","og_image":[{"url":"https:\/\/www.vegaengineering.com\/assets\/get_img.php?data=\/uploads\/servizi\/26.jpg&width_output=200&height_output=150","type":"","width":"","height":""}],"author":"CFD FEA SERVICE","twitter_card":"summary_large_image","twitter_misc":{"Written by":"CFD FEA SERVICE","Estimated reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/#article","isPartOf":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/"},"author":{"name":"CFD FEA SERVICE","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7"},"headline":"VALUTAZIONE DEL RISCHIO DA MOVIMENTAZIONE MANUALE DEI CARICHI, TRAINO SPINTA, MOVIMENTI RIPETITIVI","datePublished":"2019-03-23T02:01:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/"},"wordCount":1417,"publisher":{"@id":"https:\/\/cfdfeaservice.it\/#organization"},"image":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vegaengineering.com\/assets\/get_img.php?data=\/uploads\/servizi\/26.jpg&width_output=200&height_output=150","articleSection":["Normativa"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/","url":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/","name":"VALUTAZIONE DEL RISCHIO DA MOVIMENTAZIONE MANUALE DEI CARICHI, TRAINO SPINTA, MOVIMENTI RIPETITIVI - CFD FEA\/FEM Service","isPartOf":{"@id":"https:\/\/cfdfeaservice.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/#primaryimage"},"image":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vegaengineering.com\/assets\/get_img.php?data=\/uploads\/servizi\/26.jpg&width_output=200&height_output=150","datePublished":"2019-03-23T02:01:24+00:00","breadcrumb":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/#primaryimage","url":"https:\/\/www.vegaengineering.com\/assets\/get_img.php?data=\/uploads\/servizi\/26.jpg&width_output=200&height_output=150","contentUrl":"https:\/\/www.vegaengineering.com\/assets\/get_img.php?data=\/uploads\/servizi\/26.jpg&width_output=200&height_output=150"},{"@type":"BreadcrumbList","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/03\/23\/valutazione-del-rischio-da-movimentazione-manuale-dei-carichi-traino-spinta-movimenti-ripetitivi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cfdfeaservice.it\/"},{"@type":"ListItem","position":2,"name":"VALUTAZIONE DEL RISCHIO DA MOVIMENTAZIONE MANUALE DEI CARICHI, TRAINO SPINTA, MOVIMENTI RIPETITIVI"}]},{"@type":"WebSite","@id":"https:\/\/cfdfeaservice.it\/#website","url":"https:\/\/cfdfeaservice.it\/","name":"CFD FEA\/FEM Service","description":"Servizi di ingegneria 4.0","publisher":{"@id":"https:\/\/cfdfeaservice.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cfdfeaservice.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cfdfeaservice.it\/#organization","name":"CFD FEA SERVICE SRL","url":"https:\/\/cfdfeaservice.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1","contentUrl":"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1","width":677,"height":178,"caption":"CFD FEA SERVICE SRL"},"image":{"@id":"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cfdfeaservice","https:\/\/www.linkedin.com\/company\/11421185\/","https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA"]},{"@type":"Person","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7","name":"CFD FEA SERVICE","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g","caption":"CFD FEA SERVICE"},"url":"https:\/\/cfdfeaservice.it\/index.php\/author\/cfd-fea-service\/"}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p9JrPq-GF","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/2645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/comments?post=2645"}],"version-history":[{"count":0,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/2645\/revisions"}],"wp:attachment":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/media?parent=2645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/categories?post=2645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/tags?post=2645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}