{"id":2695,"date":"2019-04-04T03:02:31","date_gmt":"2019-04-04T01:02:31","guid":{"rendered":"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/"},"modified":"2019-04-04T03:02:31","modified_gmt":"2019-04-04T01:02:31","slug":"il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo","status":"publish","type":"post","link":"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/","title":{"rendered":"Il Cnappc firma un protocollo d\u2019Intesa con Spagna e Portogallo"},"content":{"rendered":"<div>\n<p>Il Consiglio Nazionale degli Architetti PPC ha firmato un protocollo d\u2019intesa con l\u2019Ordine degli Architetti del Portogallo e il Consiglio superiore dei Collegi degli architetti di Spagna per sviluppare proposte ed iniziative comuni finalizzate a migliorare la promozione della figura dell\u2019architetto e l\u2019esercizio della professionale anche attraverso interventi presso organizzazioni e istituzioni europee.<\/p>\n<h3>L\u2019accordo fra i tre Paesi vuole incrementare e consolidare i rapporti di collaborazione e di condivisione di esperienze, strutturando i suoi obiettivi in due aree:<\/h3>\n<ul>\n<li>\n<h4>il rafforzamento della conoscenza e della riflessione condivisa per trattare temi specifici (come per esempio l\u2019accesso alla professione, la pratica professionale, la mobilit\u00e0 e la libera circolazione dei professionisti, la formazione continua, le buone pratiche sull\u2019Agenda Urbana, azioni culturali e politiche sull\u2019innovazione e del lavoro) favorendo lo scambio di esperienze e buone pratiche, creando un quadro che faciliti, ove opportuno, azioni di cooperazione congiunta ritenute necessarie e convenienti;<\/h4>\n<\/li>\n<li>\n<h4>il coordinamento della rappresentanza internazionale in organizzazioni e forum di ambito europeo e mondiale come criterio generale e, in forma specifica, per quelle tematiche, che di comune accordo tra le parti, verranno fissate.<\/h4>\n<\/li>\n<\/ul>\n<h3>L\u2019accordo sar\u00e0 attuato mediante:<\/h3>\n<ul>\n<li>\n<h4>incontri periodici, ogni sei mesi, per la coordinazione e cooperazione condivisa;<\/h4>\n<\/li>\n<li>\n<h4>attivit\u00e0 di approfondimento su tematiche di interesse comune relative alla professione da proporre agli organismo Internazionali (UIA, CAE, UMAR);<\/h4>\n<\/li>\n<li>\n<h4>diffusione tra gli architetti dei tre Paesi di questo accordo e delle iniziative ad esso connesse.<\/h4>\n<\/li>\n<\/ul>\n<p>L&#8217;articolo <a rel=\"nofollow\" href=\"https:\/\/www.unioneingegneri.com\/protocollo-dintesa-con-spagna-e-portogallo-accordo-storico-del-cnappc\/\">Il Cnappc firma un protocollo d\u2019Intesa con Spagna e Portogallo<\/a> proviene da <a rel=\"nofollow\" href=\"https:\/\/www.unioneingegneri.com\/\">Unione Geometri<\/a>.<\/p>\n<\/div>\n<p><a href=\"https:\/\/www.unionearchitetti.com\/protocollo-dintesa-con-spagna-e-portogallo-accordo-storico-del-cnappc\">Vai alla fonte.<\/a><\/p>\n<p>Autore: Mauro Melis<\/p>\n<p class=\"wpematico_credit\"><small>Powered by <a href=\"http:\/\/www.wpematico.com\" target=\"_blank\" rel=\"noopener noreferrer\">WPeMatico<\/a><\/small><\/p>\n<p><strong>_________________________________<\/strong><\/p>\n<p><strong>CFD FEA Service SRL<\/strong> &egrave; una societ&agrave; di servizi che offre <em>consulenza<\/em> e <em>formazione<\/em> in ambito <strong>ingegneria<\/strong> e <strong>IT<\/strong>. Se questo post\/prodotto ti &egrave; piaciuto ti invitiamo a:<\/p>\n<ul>\n<li>visionare il nostro <a href=\"https:\/\/cfdfeaservice.it\/index.php\/blog\/\" target=\"_blank\" rel=\"noopener\">blog<\/a><\/li>\n<li>visionare i <a href=\"https:\/\/cfdfeaservice.it\/index.php\/prodotti\/\" target=\"_blank\" rel=\"noopener\">software<\/a> disponibili - anche per la formazione<\/li>\n<li>iscriverti alla nostra newsletter<\/li>\n<li>entrare in contatto con noi attraverso la <a href=\"https:\/\/cfdfeaservice.it\/#ribbon\" target=\"_blank\" rel=\"noopener\">pagina contatti<\/a><\/li>\n<\/ul>\n<p>Saremo lieti di seguire le tue richieste e fornire risposte alle tue domande.<\/p>","protected":false},"excerpt":{"rendered":"<p>Il Consiglio Nazionale degli Architetti PPC ha firmato un protocollo d\u2019intesa con l\u2019Ordine degli Architetti del Portogallo e il Consiglio superiore dei Collegi degli architetti di Spagna per sviluppare proposte ed iniziative comuni finalizzate a migliorare la promozione della figura dell\u2019architetto e l\u2019esercizio della professionale anche attraverso interventi presso organizzazioni [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[57],"tags":[],"class_list":["post-2695","post","type-post","status-publish","format-standard","hentry","category-normativa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Cnappc firma un protocollo d\u2019Intesa con Spagna e Portogallo - CFD FEA\/FEM Service<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Cnappc firma un protocollo d\u2019Intesa con Spagna e Portogallo - CFD FEA\/FEM Service\" \/>\n<meta property=\"og:description\" content=\"Il Consiglio Nazionale degli Architetti PPC ha firmato un protocollo d\u2019intesa con l\u2019Ordine degli Architetti del Portogallo e il Consiglio superiore dei Collegi degli architetti di Spagna per sviluppare proposte ed iniziative comuni finalizzate a migliorare la promozione della figura dell\u2019architetto e l\u2019esercizio della professionale anche attraverso interventi presso organizzazioni [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/\" \/>\n<meta property=\"og:site_name\" content=\"CFD FEA\/FEM Service\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cfdfeaservice\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-04T01:02:31+00:00\" \/>\n<meta name=\"author\" content=\"CFD FEA SERVICE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"CFD FEA SERVICE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/\"},\"author\":{\"name\":\"CFD FEA SERVICE\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\"},\"headline\":\"Il Cnappc firma un protocollo d\u2019Intesa con Spagna e Portogallo\",\"datePublished\":\"2019-04-04T01:02:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/\"},\"wordCount\":275,\"publisher\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\"},\"articleSection\":[\"Normativa\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/\",\"url\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/\",\"name\":\"Il Cnappc firma un protocollo d\u2019Intesa con Spagna e Portogallo - CFD FEA\/FEM Service\",\"isPartOf\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#website\"},\"datePublished\":\"2019-04-04T01:02:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cfdfeaservice.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Cnappc firma un protocollo d\u2019Intesa con Spagna e Portogallo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cfdfeaservice.it\/#website\",\"url\":\"https:\/\/cfdfeaservice.it\/\",\"name\":\"CFD FEA\/FEM Service\",\"description\":\"Servizi di ingegneria 4.0\",\"publisher\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cfdfeaservice.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cfdfeaservice.it\/#organization\",\"name\":\"CFD FEA SERVICE SRL\",\"url\":\"https:\/\/cfdfeaservice.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"contentUrl\":\"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"width\":677,\"height\":178,\"caption\":\"CFD FEA SERVICE SRL\"},\"image\":{\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cfdfeaservice\",\"https:\/\/www.linkedin.com\/company\/11421185\/\",\"https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\",\"name\":\"CFD FEA SERVICE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/cfdfeaservice.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"caption\":\"CFD FEA SERVICE\"},\"url\":\"https:\/\/cfdfeaservice.it\/index.php\/author\/cfd-fea-service\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Cnappc firma un protocollo d\u2019Intesa con Spagna e Portogallo - CFD FEA\/FEM Service","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/","og_locale":"en_GB","og_type":"article","og_title":"Il Cnappc firma un protocollo d\u2019Intesa con Spagna e Portogallo - CFD FEA\/FEM Service","og_description":"Il Consiglio Nazionale degli Architetti PPC ha firmato un protocollo d\u2019intesa con l\u2019Ordine degli Architetti del Portogallo e il Consiglio superiore dei Collegi degli architetti di Spagna per sviluppare proposte ed iniziative comuni finalizzate a migliorare la promozione della figura dell\u2019architetto e l\u2019esercizio della professionale anche attraverso interventi presso organizzazioni [&hellip;]","og_url":"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/","og_site_name":"CFD FEA\/FEM Service","article_publisher":"https:\/\/www.facebook.com\/cfdfeaservice","article_published_time":"2019-04-04T01:02:31+00:00","author":"CFD FEA SERVICE","twitter_card":"summary_large_image","twitter_misc":{"Written by":"CFD FEA SERVICE","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/#article","isPartOf":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/"},"author":{"name":"CFD FEA SERVICE","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7"},"headline":"Il Cnappc firma un protocollo d\u2019Intesa con Spagna e Portogallo","datePublished":"2019-04-04T01:02:31+00:00","mainEntityOfPage":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/"},"wordCount":275,"publisher":{"@id":"https:\/\/cfdfeaservice.it\/#organization"},"articleSection":["Normativa"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/","url":"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/","name":"Il Cnappc firma un protocollo d\u2019Intesa con Spagna e Portogallo - CFD FEA\/FEM Service","isPartOf":{"@id":"https:\/\/cfdfeaservice.it\/#website"},"datePublished":"2019-04-04T01:02:31+00:00","breadcrumb":{"@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cfdfeaservice.it\/index.php\/2019\/04\/04\/il-cnappc-firma-un-protocollo-dintesa-con-spagna-e-portogallo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cfdfeaservice.it\/"},{"@type":"ListItem","position":2,"name":"Il Cnappc firma un protocollo d\u2019Intesa con Spagna e Portogallo"}]},{"@type":"WebSite","@id":"https:\/\/cfdfeaservice.it\/#website","url":"https:\/\/cfdfeaservice.it\/","name":"CFD FEA\/FEM Service","description":"Servizi di ingegneria 4.0","publisher":{"@id":"https:\/\/cfdfeaservice.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cfdfeaservice.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cfdfeaservice.it\/#organization","name":"CFD FEA SERVICE SRL","url":"https:\/\/cfdfeaservice.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1","contentUrl":"https:\/\/i2.wp.com\/cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1","width":677,"height":178,"caption":"CFD FEA SERVICE SRL"},"image":{"@id":"https:\/\/cfdfeaservice.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cfdfeaservice","https:\/\/www.linkedin.com\/company\/11421185\/","https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA"]},{"@type":"Person","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7","name":"CFD FEA SERVICE","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cfdfeaservice.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g","caption":"CFD FEA SERVICE"},"url":"https:\/\/cfdfeaservice.it\/index.php\/author\/cfd-fea-service\/"}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p9JrPq-Ht","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/2695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/comments?post=2695"}],"version-history":[{"count":0,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/2695\/revisions"}],"wp:attachment":[{"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/media?parent=2695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/categories?post=2695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/tags?post=2695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}